{"id":175801,"date":"2022-05-06T14:44:49","date_gmt":"2022-05-06T13:44:49","guid":{"rendered":"https:\/\/moodmedia.com\/non-categorizzato\/ristorante-av-come-ottenere-il-massimo-per-i-vostri-soldi\/"},"modified":"2024-12-03T16:21:24","modified_gmt":"2024-12-03T16:21:24","slug":"ristorante-av-come-ottenere-il-massimo-per-i-vostri-soldi","status":"publish","type":"post","link":"https:\/\/moodmedia.com\/it\/risorse-it\/ristorante-av-come-ottenere-il-massimo-per-i-vostri-soldi\/","title":{"rendered":"Ristorante AV &#8211; Come ottenere il massimo per i vostri soldi"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.0&#8243; background_color=&#8221;rgba(0,0,0,0.45)&#8221; background_image=&#8221;https:\/\/moodmedia.com\/wp-content\/uploads\/2022\/05\/shutterstock_1051465628-copy.jpg&#8221; background_blend=&#8221;multiply&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.27.0&#8243; background_layout=&#8221;dark&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1 class=\"bold new-hero-ext\">Ristorante AV &#8211; Come ottenere il massimo per i tuoi soldi<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,2_3&#8243; _builder_version=&#8221;4.16&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.27.0&#8243; background_layout=&#8221;dark&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p class=\"intro2 bold moodblue\">Il tuo sistema AV potrebbe non essere cos\u00ec importante come la griglia o i forni, ma non \u00e8 da trascurare. Dopo tutto, un ottimo design, altoparlanti di qualit\u00e0 e schermi ad alte prestazioni sono ingredienti fondamentali per creare un&#8217;esperienza culinaria memorabile e coinvolgente. <\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;2_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.27.0&#8243; background_layout=&#8221;dark&#8221; global_colors_info=&#8221;{}&#8221;]Ma proprio come il tuo ristorante \u00e8 diverso da qualsiasi altro, non ci sono due sistemi AV esattamente uguali.<br \/>\nAnche quando si tratta di catene di ristoranti ci sono leggere variazioni nel design e nella funzione di ogni sistema, e ci sono una serie di considerazioni che dovrai fare se vuoi ottenere il miglior sistema per le tue esigenze e il tuo budget.<br \/>\nLi scomponiamo tutti di seguito e forniamo alcune intuizioni dai nostri specialisti AV interni.[\/et_pb_text][et_pb_button button_url=&#8221;https:\/\/us.moodmedia.com\/wp-content\/uploads\/2019\/06\/Restaurant-AV-How-to-Get-the-Most-for-your-Money-6-5.pdf&#8221; url_new_window=&#8221;on&#8221; button_text=&#8221;Scarica questo articolo&#8221; button_alignment=&#8221;left&#8221; _builder_version=&#8221;4.27.0&#8243; custom_button=&#8221;on&#8221; button_text_color=&#8221;#ffffff&#8221; button_bg_color=&#8221;#cd102f&#8221; button_border_color=&#8221;#cd102f&#8221; button_icon=&#8221;&#x3d;||divi||400&#8243; button_icon_color=&#8221;#cd102f&#8221; hover_enabled=&#8221;0&#8243; button_text_color_hover=&#8221;#cd102f&#8221; button_border_color_hover=&#8221;#ffffff&#8221; button_bg_color_hover=&#8221;#ffffff&#8221; saved_tabs=&#8221;all&#8221; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;on&#8221; button_text_color__hover=&#8221;#cd102f&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;on&#8221; button_border_color__hover=&#8221;#ffffff&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;on&#8221; button_bg_color__hover=&#8221;#ffffff&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221; module_class=&#8221;mbutton&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.27.0&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3 class=\"bold moodblue\">#1: Definisci il tuo &#8220;prime time&#8221; &#8211; come appare e come suona.<\/h3>\n<p>Ogni ristorante prospera grazie a una prima serata unica.<br \/>\nPer esempio, i bar sportivi prosperano di pi\u00f9 il sabato e la domenica, quando ci sono tutte le grandi partite.<br \/>\nD&#8217;altra parte, i ristoranti raffinati sono tipicamente al loro pi\u00f9 affollato gioved\u00ec-sabato sera.  <\/p>\n<p>Gib Harris, direttore delle vendite di sistemi di Mood Media, sottolinea l&#8217;importanza di comprendere l&#8217;esperienza che stai cercando di creare nei momenti di maggiore affluenza. &#8220;<em>Chiedo sempre ai miei clienti: &#8220;come appare e suona l&#8217;esperienza durante i vostri momenti migliori?&#8221; La musica \u00e8 al centro dell&#8217;esperienza o \u00e8 in sottofondo per creare un&#8217;atmosfera specifica?<br \/>\nStai cercando di far sentire i clienti come se fossero alla grande partita?<br \/>\nCome minimo, il vostro sistema audiovisivo deve fornire prestazioni adeguate per sostenere l&#8217;esperienza in prima serata.  <\/em>&#8220;<\/p>\n<p>&nbsp;<\/p>\n<h3 class=\"bold moodblue\">#2: Definisci la tua clientela<\/h3>\n<p>Prima di investire nel vostro sistema AV per ristoranti, dovreste considerare la vostra clientela e che tipo di esperienza si aspetta nella vostra attivit\u00e0.<\/p>\n<p>Per esempio, la classe medio-alta della generazione X non sta cercando schermi in tutta la sala da pranzo e musica a tutto volume nel suo ristorante italiano preferito.<br \/>\nVogliono avere una conversazione informale mentre sorseggiano vino e godono di ottimi pasti.<br \/>\nTuttavia, i millennials che frequentano il tuo locale di sushi a tarda notte probabilmente apprezzeranno la musica dance ad alto volume e le immagini d&#8217;ambiente sulle pareti.<br \/>\nSe sono seduti al sushi bar, allora vorranno anche guardare un po&#8217; di TV mentre parlano.<br \/>\nRicorda &#8211; la tua clientela \u00e8 unica come il tuo marchio, e l&#8217;esperienza che crei \u00e8 tutta una questione di catering per le loro preferenze in modo che siano pi\u00f9 propensi a tornare.    <\/p>\n<p>&nbsp;<\/p>\n<h3 class=\"bold moodblue\">#3: Conoscere la propria copertura.<\/h3>\n<p>Quando parliamo di copertura, ci riferiamo a quanto spazio e quali aree sono coperte dall&#8217;audiovisivo.<br \/>\nPotresti non aver bisogno di altoparlanti in ogni area del tuo ristorante, e potresti volere degli schermi solo all&#8217;ingresso e vicino al bar.<br \/>\nPassate attraverso il vostro edificio e fate una lista delle stanze e delle aree di ogni stanza dove l&#8217;audiovisivo avr\u00e0 una presenza.<br \/>\nConsiderate anche le aree da pranzo all&#8217;aperto e assicuratevi di considerare diverse variazioni per il posizionamento degli altoparlanti e dello schermo.<br \/>\nLa copertura determina il design, il posizionamento e l&#8217;hardware specifico necessario per soddisfare le vostre esigenze.    <\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.0&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3 class=\"bold moodblue\">#4: Conoscere la propria funzione.<\/h3>\n<p>In poche parole, la funzione si riferisce a ci\u00f2 che le vostre soluzioni faranno. Per esempio, volete che i vostri schermi riproducano la TV o mostrino la segnaletica digitale? Volete che facciano entrambe le cose? Vuoi la funzionalit\u00e0 PA nella tua cucina? O forse state cercando di creare un&#8217;esperienza simile al teatro nel vostro bar sportivo per i giorni delle partite. Come ha detto Greg Gershon, VP delle vendite di sistema di Mood Mediala comprensione delle funzionalit\u00e0 di cui hai bisogno ti aiuter\u00e0 a ottenere il miglior valore.<\/p>\n<p>&#8220;L&#8217;importanza di sapere come volete che il vostro sistema AV funzioni non pu\u00f2 essere sottovalutata&#8221;, dice Greg.<br \/>\n&#8220;Se avete una visione della funzionalit\u00e0 di cui avete bisogno, il vostro fornitore AV sar\u00e0 meglio attrezzato per guidarvi verso i componenti e la qualit\u00e0 giusti per le vostre esigenze e il vostro budget&#8221;. <\/p>\n<p>&nbsp;<\/p>\n<h3 class=\"bold moodblue\">#5: Esigere il grado commerciale.<\/h3>\n<p>C&#8217;\u00e8 un&#8217;importante differenza tra l&#8217;attrezzatura di livello commerciale e l&#8217;AV domestico, e vorrete andare con la prima se volete davvero ottenere il massimo per i vostri soldi.<\/p>\n<p>Schermi, altoparlanti e amplificatori di livello commerciale sono progettati per funzionare in modo affidabile per diverse ore al giorno, 365 giorni all&#8217;anno.<br \/>\nInoltre, gli schermi di tipo commerciale hanno un involucro protettivo che garantisce alte prestazioni anche in un ambiente di ristorazione. <\/p>\n<p>Un altoparlante scoppiettante o un display sfocato sui vostri schermi piatti non far\u00e0 sbattere i tovaglioli sul tavolo agli ospiti e non li far\u00e0 uscire.<br \/>\nTuttavia, questo tipo di qualit\u00e0 dar\u00e0 ai vostri ospiti una cattiva impressione del vostro ristorante &#8211; indipendentemente dal fatto che il vostro cibo sia buono o meno. <\/p>\n<p>Assicuratevi di investire in attrezzature di alta qualit\u00e0 e di <strong>livello commerciale<\/strong> di marche come Bose, Klipsch, LG, Samsung e altre che si concentrano su applicazioni commerciali.<br \/>\nQuesti produttori sanno come progettare le loro linee di prodotti professionali per la massima performance e affidabilit\u00e0 in un ambiente di ristorazione. <\/p>\n<p>Inoltre, se avete pi\u00f9 sedi, andare con un produttore di livello commerciale pu\u00f2 fornirvi l&#8217;opportunit\u00e0 di ricevere sconti acquistando o noleggiando attrezzature all&#8217;ingrosso.<\/p>\n<p>&nbsp;<\/p>\n<h3 class=\"bold moodblue\">#6: Portate un esperto AV qualificato per i ristoranti.<\/h3>\n<p>Questo punto probabilmente va da s\u00e9, ma \u00e8 comunque importante da menzionare.<br \/>\nL&#8217;industria AV \u00e8 piena di grandi progettisti e installatori, ma \u00e8 nel vostro migliore interesse trovare un&#8217;azienda con esperienza specifica nella fornitura di <a href=\"https:\/\/us.moodmedia.com\/systems\/audiovisual-solutions\/\">soluzioni audiovisive<\/a> per ristoranti, perch\u00e9 capiscono come progettare correttamente un sistema rispetto alle esigenze di un ambiente di ristorazione.<br \/>\nTi faranno le domande giuste e, di conseguenza, ti consiglieranno l&#8217;attrezzatura giusta per le tue esigenze, lo spazio e il budget.  <\/p>\n<p>Ricordate &#8211; il vostro fornitore AV dovrebbe agire anche come consulente.<br \/>\nSe vi siete presi il tempo di lavorare attraverso i cinque passi precedenti prima della vostra consultazione, allora darete pi\u00f9 potere all&#8217;esperto AV di progettare e installare un sistema che porta la vostra visione alla vita. <\/p>\n<p>&nbsp;<\/p>\n<h3 class=\"bold moodblue\">#7: avere una mente aperta.<\/h3>\n<p>Non importa quanto sia specifica la vostra visione, \u00e8 importante mantenere una mente aperta durante la consultazione. Proponete la vostra visione e lasciate che il professionista AV condivida la sua esperienza e faccia altre domande. Queste persone vivono e respirano l&#8217;audiovisivo, e capiscono esattamente come aiutarvi a creare un&#8217;esperienza che i vostri ospiti vorranno ripetere &#8211; ancora e ancora.<\/p>\n<p class=\"intro2\"><strong><br \/>\n  <a href=\"https:\/\/us.moodmedia.com\/contact-us\/solution-information-requests\/\">Contattateci<\/a><br \/>\n<\/strong> oggi per fissare una consultazione gratuita con uno dei nostri professionisti AV per ristoranti. Abbiamo installato pi\u00f9 sistemi audiovisivi per ristoranti di qualsiasi altro fornitore al mondo, e vi aiuteremo a trovare i componenti giusti per le vostre esigenze e il vostro budget.<\/p>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;https:\/\/us.moodmedia.com\/wp-content\/uploads\/2019\/06\/Restaurant-AV-How-to-Get-the-Most-for-your-Money-6-5.pdf&#8221; url_new_window=&#8221;on&#8221; button_text=&#8221;Scarica questo articolo&#8221; button_alignment=&#8221;left&#8221; _builder_version=&#8221;4.27.0&#8243; custom_button=&#8221;on&#8221; button_text_color=&#8221;#ffffff&#8221; button_bg_color=&#8221;#cd102f&#8221; button_border_color=&#8221;#cd102f&#8221; button_icon=&#8221;&#x3d;||divi||400&#8243; button_icon_color=&#8221;#cd102f&#8221; hover_enabled=&#8221;0&#8243; button_text_color_hover=&#8221;#cd102f&#8221; button_border_color_hover=&#8221;#ffffff&#8221; button_bg_color_hover=&#8221;#ffffff&#8221; saved_tabs=&#8221;all&#8221; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;on&#8221; button_text_color__hover=&#8221;#cd102f&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;on&#8221; button_border_color__hover=&#8221;#ffffff&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;on&#8221; button_bg_color__hover=&#8221;#ffffff&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221; module_class=&#8221;mbutton&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Industry Page Contact&#8221; module_id=&#8221;contact&#8221; _builder_version=&#8221;4.15&#8243; global_module=&#8221;169058&#8243; collapsed=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.27.0&#8243; text_font=&#8221;||||||||&#8221; text_orientation=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2 class=\"bold\">CONNETTITI CON NOI<\/h2>\n<h4 class=\"intro\">Contattateci oggi stesso e migliorate l&#8217;esperienza del cliente nella vostra azienda.<\/h4>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Short Contact Form (light background)&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<script>\nvar gform;gform||(document.addEventListener(\"gform_main_scripts_loaded\",function(){gform.scriptsLoaded=!0}),document.addEventListener(\"gform\/theme\/scripts_loaded\",function(){gform.themeScriptsLoaded=!0}),window.addEventListener(\"DOMContentLoaded\",function(){gform.domLoaded=!0}),gform={domLoaded:!1,scriptsLoaded:!1,themeScriptsLoaded:!1,isFormEditor:()=>\"function\"==typeof InitializeEditor,callIfLoaded:function(o){return!(!gform.domLoaded||!gform.scriptsLoaded||!gform.themeScriptsLoaded&&!gform.isFormEditor()||(gform.isFormEditor()&&console.warn(\"The use of gform.initializeOnLoaded() is deprecated in the form editor context and will be removed in Gravity Forms 3.1.\"),o(),0))},initializeOnLoaded:function(o){gform.callIfLoaded(o)||(document.addEventListener(\"gform_main_scripts_loaded\",()=>{gform.scriptsLoaded=!0,gform.callIfLoaded(o)}),document.addEventListener(\"gform\/theme\/scripts_loaded\",()=>{gform.themeScriptsLoaded=!0,gform.callIfLoaded(o)}),window.addEventListener(\"DOMContentLoaded\",()=>{gform.domLoaded=!0,gform.callIfLoaded(o)}))},hooks:{action:{},filter:{}},addAction:function(o,r,e,t){gform.addHook(\"action\",o,r,e,t)},addFilter:function(o,r,e,t){gform.addHook(\"filter\",o,r,e,t)},doAction:function(o){gform.doHook(\"action\",o,arguments)},applyFilters:function(o){return gform.doHook(\"filter\",o,arguments)},removeAction:function(o,r){gform.removeHook(\"action\",o,r)},removeFilter:function(o,r,e){gform.removeHook(\"filter\",o,r,e)},addHook:function(o,r,e,t,n){null==gform.hooks[o][r]&&(gform.hooks[o][r]=[]);var d=gform.hooks[o][r];null==n&&(n=r+\"_\"+d.length),gform.hooks[o][r].push({tag:n,callable:e,priority:t=null==t?10:t})},doHook:function(r,o,e){var t;if(e=Array.prototype.slice.call(e,1),null!=gform.hooks[r][o]&&((o=gform.hooks[r][o]).sort(function(o,r){return o.priority-r.priority}),o.forEach(function(o){\"function\"!=typeof(t=o.callable)&&(t=window[t]),\"action\"==r?t.apply(null,e):e[0]=t.apply(null,e)})),\"filter\"==r)return e[0]},removeHook:function(o,r,t,n){var e;null!=gform.hooks[o][r]&&(e=(e=gform.hooks[o][r]).filter(function(o,r,e){return!!(null!=n&&n!=o.tag||null!=t&&t!=o.priority)}),gform.hooks[o][r]=e)}});\n<\/script>\n\n                <div class='gf_browser_gecko gform_wrapper gravity-theme gform-theme--no-framework' data-form-theme='gravity-theme' data-form-index='0' id='gform_wrapper_3' >\n                        <div class='gform_heading'>\n\t\t\t\t\t\t\t<p class='gform_required_legend'>&quot;<span class=\"gfield_required gfield_required_asterisk\">*<\/span>&quot; indica i campi obbligatori<\/p>\n                        <\/div><form method='post' enctype='multipart\/form-data'  id='gform_3'  action='\/it\/wp-json\/wp\/v2\/posts\/175801' data-formid='3' novalidate>\n                        <div class='gform-body gform_body'><div id='gform_fields_3' class='gform_fields top_label form_sublabel_below description_below validation_below'><div id=\"field_3_41\" class=\"gfield gfield--type-honeypot gform_validation_container field_sublabel_below gfield--has-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_3_41'>LinkedIn<\/label><div class='ginput_container'><input name='input_41' id='input_3_41' type='text' value='' autocomplete='new-password'\/><\/div><div class='gfield_description' id='gfield_description_3_41'>Questo campo serve per la convalida e dovrebbe essere lasciato inalterato.<\/div><\/div><fieldset id=\"field_3_1\" class=\"gfield gfield--type-name gfield--input-type-name gfield_contains_required field_sublabel_hidden_label gfield--no-description field_description_below hidden_label field_validation_below gfield_visibility_visible\"  ><legend class='gfield_label gform-field-label gfield_label_before_complex' >Nome<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/legend><div class='ginput_complex ginput_container ginput_container--name no_prefix has_first_name no_middle_name has_last_name no_suffix gf_name_has_2 ginput_container_name gform-grid-row' id='input_3_1'>\n                            \n                            <span id='input_3_1_3_container' class='name_first gform-grid-col gform-grid-col--size-auto' >\n                                                    <input type='text' name='input_1.3' id='input_3_1_3' value=''   aria-required='true'   placeholder='Nome'  \/>\n                                                    <label for='input_3_1_3' class='gform-field-label gform-field-label--type-sub hidden_sub_label screen-reader-text'>Nome<\/label>\n                                                <\/span>\n                            \n                            <span id='input_3_1_6_container' class='name_last gform-grid-col gform-grid-col--size-auto' >\n                                                    <input type='text' name='input_1.6' id='input_3_1_6' value=''   aria-required='true'   placeholder='Cognome'  \/>\n                                                    <label for='input_3_1_6' class='gform-field-label gform-field-label--type-sub hidden_sub_label screen-reader-text'>Cognome<\/label>\n                                                <\/span>\n                            \n                        <\/div><\/fieldset><div id=\"field_3_2\" class=\"gfield gfield--type-email gfield--input-type-email gfield--width-half gfield_contains_required field_sublabel_below gfield--no-description field_description_below hidden_label field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_3_2'>Email<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_email'>\n                            <input name='input_2' id='input_3_2' type='email' value='' class='large'   placeholder='Email' aria-required=\"true\" aria-invalid=\"false\"  \/>\n                        <\/div><\/div><div id=\"field_3_4\" class=\"gfield gfield--type-phone gfield--input-type-phone gfield--width-half gfield_contains_required field_sublabel_below gfield--no-description field_description_below hidden_label field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_3_4'>Telefono<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_phone'><input name='input_4' id='input_3_4' type='tel' value='' class='large'  placeholder='Telefono' aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/div><div id=\"field_3_3\" class=\"gfield gfield--type-text gfield--input-type-text gfield--width-half gfield_contains_required field_sublabel_below gfield--no-description field_description_below hidden_label field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_3_3'>Nome della societ\u00e0<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_3' id='input_3_3' type='text' value='' class='large'    placeholder='Nome della societ\u00e0' aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/div><div id=\"field_3_9\" class=\"gfield gfield--type-select gfield--input-type-select gfield--width-half gfield_contains_required field_sublabel_below gfield--no-description field_description_below hidden_label field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_3_9'>Numero di sedi<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_select'><select name='input_9' id='input_3_9' class='large gfield_select'    aria-required=\"true\" aria-invalid=\"false\" ><option value='' selected='selected' class='gf_placeholder'>Numero di sedi<\/option><option value='1' >1<\/option><option value='2-10' >2-10<\/option><option value='11-49' >11-49<\/option><option value='50+' >50+<\/option><\/select><\/div><\/div><div id=\"field_3_6\" class=\"gfield gfield--type-textarea gfield--input-type-textarea field_sublabel_below gfield--no-description field_description_below hidden_label field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_3_6'>Come possiamo aiutarvi?<\/label><div class='ginput_container ginput_container_textarea'><textarea name='input_6' id='input_3_6' class='textarea small'    placeholder='Come possiamo aiutarvi?'  aria-invalid=\"false\"   rows='10' cols='50'><\/textarea><\/div><\/div><fieldset id=\"field_3_14\" class=\"gfield gfield--type-consent gfield--type-choice gfield--input-type-consent gfield--width-full gfield_contains_required field_sublabel_below gfield--no-description field_description_below hidden_label field_validation_below gfield_visibility_visible\"  ><legend class='gfield_label gform-field-label gfield_label_before_complex' >Informativa sulla privacy<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/legend><div class='ginput_container ginput_container_consent'><input name='input_14.1' id='input_3_14_1' type='checkbox' value='1'   aria-required=\"true\" aria-invalid=\"false\"   \/> <label class=\"gform-field-label gform-field-label--type-inline gfield_consent_label\" for='input_3_14_1' >Accetto il trattamento dei miei dati personali in conformit\u00e0 con l'<a href=\"https:\/\/moodmedia.com\/it\/azienda\/politica-sulla-privacy\/\" target=\"_blank\">Informativa sulla privacy<\/a> (compresi i trasferimenti internazionali) e acconsento all'utilizzo delle informazioni da parte di Mood Media per contattarmi.<span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/label><input type='hidden' name='input_14.2' value='Accetto il trattamento dei miei dati personali in conformit\u00e0 con l&#039;&lt;a href=&quot;https:\/\/moodmedia.com\/it\/azienda\/politica-sulla-privacy\/&quot; target=&quot;_blank&quot;&gt;Informativa sulla privacy&lt;\/a&gt; (compresi i trasferimenti internazionali) e acconsento all&#039;utilizzo delle informazioni da parte di Mood Media per contattarmi.' class='gform_hidden' \/><input type='hidden' name='input_14.3' value='3' class='gform_hidden' \/><\/div><\/fieldset><fieldset id=\"field_3_15\" class=\"gfield gfield--type-consent gfield--type-choice gfield--input-type-consent gfield--width-full field_sublabel_below gfield--no-description field_description_below hidden_label field_validation_below gfield_visibility_visible\"  ><legend class='gfield_label gform-field-label gfield_label_before_complex' >Rimanere in contatto<\/legend><div class='ginput_container ginput_container_consent'><input name='input_15.1' id='input_3_15_1' type='checkbox' value='1'    aria-invalid=\"false\"   \/> <label class=\"gform-field-label gform-field-label--type-inline gfield_consent_label\" for='input_3_15_1' >Desidero ricevere via e-mail notizie rilevanti, informazioni sui prodotti o offerte speciali. \u00c8 possibile annullare l'iscrizione in qualsiasi momento utilizzando gli appositi link presenti in tutte le informazioni inviate.<\/label><input type='hidden' name='input_15.2' value='Desidero ricevere via e-mail notizie rilevanti, informazioni sui prodotti o offerte speciali. \u00c8 possibile annullare l&#039;iscrizione in qualsiasi momento utilizzando gli appositi link presenti in tutte le informazioni inviate.' class='gform_hidden' \/><input type='hidden' name='input_15.3' value='3' class='gform_hidden' \/><\/div><\/fieldset><div id=\"field_3_18\" class=\"gfield gfield--type-captcha gfield--input-type-captcha gfield--width-full field_sublabel_below gfield--no-description field_description_below hidden_label field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_3_18'>CAPTCHA<\/label><div id='input_3_18' class='ginput_container ginput_recaptcha' data-sitekey='6Lfv6n8bAAAAAEtmA_JMn8-9T65gbem1F5Q9T6fQ'  data-theme='light' data-tabindex='-1' data-size='invisible' data-badge='bottomright'><\/div><\/div><div id=\"field_3_24\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gfield--width-full gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_24' id='input_3_24' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='Web - INTL' \/><\/div><\/div><div id=\"field_3_17\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_17' id='input_3_17' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='it' \/><\/div><\/div><div id=\"field_3_39\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gfield--width-full gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_39' id='input_3_39' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/div><div id=\"field_3_20\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gfield--width-full gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_20' id='input_3_20' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/div><div id=\"field_3_21\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gfield--width-full gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_21' id='input_3_21' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/div><div id=\"field_3_19\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gfield--width-full gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_19' id='input_3_19' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/div><div id=\"field_3_23\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gfield--width-full gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_23' id='input_3_23' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/div><div id=\"field_3_22\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gfield--width-full gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_22' id='input_3_22' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/div><div id=\"field_3_36\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gfield--width-full gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_36' id='input_3_36' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/div><div id=\"field_3_16\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gfield--width-full gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_16' id='input_3_16' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='https:\/\/moodmedia.com\/it\/wp-json\/wp\/v2\/posts\/175801' \/><\/div><\/div><div id=\"field_3_28\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gfield--width-full gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_28' id='input_3_28' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='https:\/\/moodmedia.com\/it\/wp-json\/wp\/v2\/posts\/175801' \/><\/div><\/div><div id=\"field_3_25\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gfield--width-full gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_25' id='input_3_25' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/div><div id=\"field_3_26\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gfield--width-full gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_26' id='input_3_26' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/div><div id=\"field_3_27\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gfield--width-full gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_27' id='input_3_27' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/div><div id=\"field_3_40\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gfield--width-full gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_40' id='input_3_40' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/div><div id=\"field_3_29\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_29' id='input_3_29' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/div><div id=\"field_3_30\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_30' id='input_3_30' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/div><div id=\"field_3_33\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gfield--width-full gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_33' id='input_3_33' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/div><div id=\"field_3_32\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gfield--width-full gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_32' id='input_3_32' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/div><div id=\"field_3_31\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_31' id='input_3_31' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/div><div id=\"field_3_34\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_34' id='input_3_34' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/div><div id=\"field_3_35\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_35' id='input_3_35' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='https:\/\/moodmedia.com\/it\/wp-json\/wp\/v2\/posts\/175801' \/><\/div><\/div><div id=\"field_3_37\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_37' id='input_3_37' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/div><div id=\"field_3_38\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_38' id='input_3_38' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/div><\/div><\/div>\n        <div class='gform-footer gform_footer top_label'> <input type=\"submit\" id=\"gform_submit_button_3\" class=\"gform_button button submit-button\" onclick=\"gform.submission.handleButtonClick(this);\" data-submission-type=\"submit\" value=\"Invia\"> \n            <input type='hidden' class='gform_hidden' name='gform_submission_method' data-js='gform_submission_method_3' value='postback' \/>\n            <input type='hidden' class='gform_hidden' name='gform_theme' data-js='gform_theme_3' id='gform_theme_3' value='gravity-theme' \/>\n            <input type='hidden' class='gform_hidden' name='gform_style_settings' data-js='gform_style_settings_3' id='gform_style_settings_3' value='[]' \/>\n            <input type='hidden' class='gform_hidden' name='is_submit_3' value='1' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submit' value='3' \/>\n            \n            <input type='hidden' class='gform_hidden' name='gform_currency' data-currency='EUR' value='fc5NtSBZs4lmbYa4uSb0wT8Sq\/VLF2WUIHudgQSxV94pjVkoG7YO3u3iwyj43elHnvZYKzPHip6G8jpsOeqtZDkbBNeuh8BUbhCt5eyQv0LUeJk=' \/>\n            <input type='hidden' class='gform_hidden' name='gform_unique_id' value='' \/>\n            <input type='hidden' class='gform_hidden' name='state_3' value='WyJ7XCIxNC4xXCI6XCIwZWI5NmJkYTliNmQ0NGVjZWM5OTk3MDgzNzFmZGFiZFwiLFwiMTQuMlwiOlwiNmRlOTAyNmVhN2JiNmE2NmQxNzNlNjgzMTVlMWRhMjlcIixcIjE0LjNcIjpcIjRiMjM4NDEzMjVlOGQ1MTU1YWJiZjJlMzg1YzhkOGFmXCIsXCIxNS4xXCI6XCIwZWI5NmJkYTliNmQ0NGVjZWM5OTk3MDgzNzFmZGFiZFwiLFwiMTUuMlwiOlwiZWVmY2JjYzBhM2FiZThhYjA0MWFkMmY4NTkyYjAwN2VcIixcIjE1LjNcIjpcIjRiMjM4NDEzMjVlOGQ1MTU1YWJiZjJlMzg1YzhkOGFmXCJ9IiwiZDJhYTlhZmNmYzNhY2U1MzA4MDk0ODEwYWM0YzQ1ZjkiXQ==' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_target_page_number_3' id='gform_target_page_number_3' value='0' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_source_page_number_3' id='gform_source_page_number_3' value='1' \/>\n            <input type='hidden' name='gform_field_values' value='' \/>\n            \n        <\/div>\n                        <\/form>\n                        <\/div><script>\ngform.initializeOnLoaded( function() {gformInitSpinner( 3, 'https:\/\/moodmedia.com\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery('#gform_ajax_frame_3').on('load',function(){var contents = jQuery(this).contents().find('*').html();var is_postback = contents.indexOf('GF_AJAX_POSTBACK') >= 0;if(!is_postback){return;}var form_content = jQuery(this).contents().find('#gform_wrapper_3');var is_confirmation = jQuery(this).contents().find('#gform_confirmation_wrapper_3').length > 0;var is_redirect = contents.indexOf('gformRedirect(){') >= 0;var is_form = form_content.length > 0 && ! is_redirect && ! is_confirmation;var mt = parseInt(jQuery('html').css('margin-top'), 10) + parseInt(jQuery('body').css('margin-top'), 10) + 100;if(is_form){jQuery('#gform_wrapper_3').html(form_content.html());if(form_content.hasClass('gform_validation_error')){jQuery('#gform_wrapper_3').addClass('gform_validation_error');} else {jQuery('#gform_wrapper_3').removeClass('gform_validation_error');}setTimeout( function() { \/* delay the scroll by 50 milliseconds to fix a bug in chrome *\/  }, 50 );if(window['gformInitDatepicker']) {gformInitDatepicker();}if(window['gformInitPriceFields']) {gformInitPriceFields();}var current_page = jQuery('#gform_source_page_number_3').val();gformInitSpinner( 3, 'https:\/\/moodmedia.com\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery(document).trigger('gform_page_loaded', [3, current_page]);window['gf_submitting_3'] = false;}else if(!is_redirect){var confirmation_content = jQuery(this).contents().find('.GF_AJAX_POSTBACK').html();if(!confirmation_content){confirmation_content = contents;}jQuery('#gform_wrapper_3').replaceWith(confirmation_content);jQuery(document).trigger('gform_confirmation_loaded', [3]);window['gf_submitting_3'] = false;wp.a11y.speak(jQuery('#gform_confirmation_message_3').text());}else{jQuery('#gform_3').append(contents);if(window['gformRedirect']) {gformRedirect();}}jQuery(document).trigger(\"gform_pre_post_render\", [{ formId: \"3\", currentPage: \"current_page\", abort: function() { this.preventDefault(); } }]);        if (event && event.defaultPrevented) {                return;        }        const gformWrapperDiv = document.getElementById( \"gform_wrapper_3\" );        if ( gformWrapperDiv ) {            const visibilitySpan = document.createElement( \"span\" );            visibilitySpan.id = \"gform_visibility_test_3\";            gformWrapperDiv.insertAdjacentElement( \"afterend\", visibilitySpan );        }        const visibilityTestDiv = document.getElementById( \"gform_visibility_test_3\" );        let postRenderFired = false;        function triggerPostRender() {            if ( postRenderFired ) {                return;            }            postRenderFired = true;            gform.core.triggerPostRenderEvents( 3, current_page );            if ( visibilityTestDiv ) {                visibilityTestDiv.parentNode.removeChild( visibilityTestDiv );            }        }        function debounce( func, wait, immediate ) {            var timeout;            return function() {                var context = this, args = arguments;                var later = function() {                    timeout = null;                    if ( !immediate ) func.apply( context, args );                };                var callNow = immediate && !timeout;                clearTimeout( timeout );                timeout = setTimeout( later, wait );                if ( callNow ) func.apply( context, args );            };        }        const debouncedTriggerPostRender = debounce( function() {            triggerPostRender();        }, 200 );        if ( visibilityTestDiv && visibilityTestDiv.offsetParent === null ) {            const observer = new MutationObserver( ( mutations ) => {                mutations.forEach( ( mutation ) => {                    if ( mutation.type === 'attributes' && visibilityTestDiv.offsetParent !== null ) {                        debouncedTriggerPostRender();                        observer.disconnect();                    }                });            });            observer.observe( document.body, {                attributes: true,                childList: false,                subtree: true,                attributeFilter: [ 'style', 'class' ],            });        } else {            triggerPostRender();        }    } );} );\n<\/script>\n\n    <script>\n        jQuery( document ).ready(function() {\n        setTimeout(() => { Cookies.get(\"traffic_source\") ? jQuery('[id=\"input_3_39\"]').val(decodeURIComponent(sanitizeInput(Cookies.get(\"traffic_source\")) ?? '')) : '';\nCookies.get(\"utm_source\") ? jQuery('[id=\"input_3_20\"]').val(decodeURIComponent(sanitizeInput(Cookies.get(\"utm_source\")) ?? '')) : '';\nCookies.get(\"utm_medium\") ? jQuery('[id=\"input_3_21\"]').val(decodeURIComponent(sanitizeInput(Cookies.get(\"utm_medium\")) ?? '')) : '';\nCookies.get(\"utm_campaign\") ? jQuery('[id=\"input_3_19\"]').val(decodeURIComponent(sanitizeInput(Cookies.get(\"utm_campaign\")) ?? '')) : '';\nCookies.get(\"utm_content\") ? jQuery('[id=\"input_3_23\"]').val(decodeURIComponent(sanitizeInput(Cookies.get(\"utm_content\")) ?? '')) : '';\nCookies.get(\"utm_term\") ? jQuery('[id=\"input_3_22\"]').val(decodeURIComponent(sanitizeInput(Cookies.get(\"utm_term\")) ?? '')) : '';\nCookies.get(\"handl_ref\") ? jQuery('[id=\"input_3_36\"]').val(decodeURIComponent(sanitizeInput(Cookies.get(\"handl_ref\")) ?? '')) : '';\nCookies.get(\"gclid\") ? jQuery('[id=\"input_3_25\"]').val(decodeURIComponent(sanitizeInput(Cookies.get(\"gclid\")) ?? '')) : '';\nCookies.get(\"fbclid\") ? jQuery('[id=\"input_3_26\"]').val(decodeURIComponent(sanitizeInput(Cookies.get(\"fbclid\")) ?? '')) : '';\nCookies.get(\"msclkid\") ? jQuery('[id=\"input_3_27\"]').val(decodeURIComponent(sanitizeInput(Cookies.get(\"msclkid\")) ?? '')) : '';\nCookies.get(\"first_traffic_source\") ? jQuery('[id=\"input_3_40\"]').val(decodeURIComponent(sanitizeInput(Cookies.get(\"first_traffic_source\")) ?? '')) : '';\nCookies.get(\"first_utm_source\") ? jQuery('[id=\"input_3_29\"]').val(decodeURIComponent(sanitizeInput(Cookies.get(\"first_utm_source\")) ?? '')) : '';\nCookies.get(\"first_utm_medium\") ? jQuery('[id=\"input_3_30\"]').val(decodeURIComponent(sanitizeInput(Cookies.get(\"first_utm_medium\")) ?? '')) : '';\nCookies.get(\"first_utm_campaign\") ? jQuery('[id=\"input_3_33\"]').val(decodeURIComponent(sanitizeInput(Cookies.get(\"first_utm_campaign\")) ?? '')) : '';\nCookies.get(\"first_utm_content\") ? jQuery('[id=\"input_3_32\"]').val(decodeURIComponent(sanitizeInput(Cookies.get(\"first_utm_content\")) ?? '')) : '';\nCookies.get(\"first_utm_term\") ? jQuery('[id=\"input_3_31\"]').val(decodeURIComponent(sanitizeInput(Cookies.get(\"first_utm_term\")) ?? '')) : '';\nCookies.get(\"handl_original_ref\") ? jQuery('[id=\"input_3_34\"]').val(decodeURIComponent(sanitizeInput(Cookies.get(\"handl_original_ref\")) ?? '')) : '';\nCookies.get(\"handl_landing_page\") ? jQuery('[id=\"input_3_35\"]').val(decodeURIComponent(sanitizeInput(Cookies.get(\"handl_landing_page\")) ?? '')) : '';\nCookies.get(\"organic_source\") ? jQuery('[id=\"input_3_37\"]').val(decodeURIComponent(sanitizeInput(Cookies.get(\"organic_source\")) ?? '')) : '';\nCookies.get(\"organic_source_str\") ? jQuery('[id=\"input_3_38\"]').val(decodeURIComponent(sanitizeInput(Cookies.get(\"organic_source_str\")) ?? '')) : '';\n }, 1000);\n        })\n    <\/script>\n    \n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ristorante AV &#8211; Come ottenere il massimo per i tuoi soldiIl tuo sistema AV potrebbe non essere cos\u00ec importante come la griglia o i forni, ma non \u00e8 da trascurare. Dopo tutto, un ottimo design, altoparlanti di qualit\u00e0 e schermi ad alte prestazioni sono ingredienti fondamentali per creare un&#8217;esperienza culinaria memorabile e coinvolgente. Ma proprio come il tuo ristorante \u00e8 diverso da qualsiasi altro, non ci sono due sistemi AV esattamente uguali. Anche quando si tratta di catene di ristoranti ci sono leggere variazioni nel design e nella funzione di ogni sistema, e ci sono una serie di considerazioni che dovrai fare se vuoi ottenere il miglior sistema per le tue esigenze e il tuo budget. Li scomponiamo tutti di seguito e forniamo alcune intuizioni dai nostri specialisti AV interni.#1: Definisci il tuo &#8220;prime time&#8221; &#8211; come appare e come suona. Ogni ristorante prospera grazie a una prima serata unica. Per esempio, i bar sportivi prosperano di pi\u00f9 il sabato e la domenica, quando ci sono tutte le grandi partite. D&#8217;altra parte, i ristoranti raffinati sono tipicamente al loro pi\u00f9 affollato gioved\u00ec-sabato sera. Gib Harris, direttore delle vendite di sistemi di Mood Media, sottolinea l&#8217;importanza di comprendere l&#8217;esperienza che stai [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":174731,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[5023,5177],"tags":[],"class_list":["post-175801","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-risorse-it","category-ristorante"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.8 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ristorante AV - Come ottenere il massimo per i vostri soldi | Mood Media Italia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ristorante AV - Come ottenere il massimo per i vostri soldi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/moodmedia.com\/it\/risorse-it\/ristorante-av-come-ottenere-il-massimo-per-i-vostri-soldi\/\" \/>\n<meta property=\"og:site_name\" content=\"Mood Media Italia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/moodmediauk\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-06T13:44:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-03T16:21:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/moodmedia.com\/wp-content\/uploads\/2022\/05\/restaurant-av-ft.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Brad Bond\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@MoodMedia_UK\" \/>\n<meta name=\"twitter:site\" content=\"@MoodMedia_UK\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Brad Bond\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/moodmedia.com\\\/it\\\/risorse-it\\\/ristorante-av-come-ottenere-il-massimo-per-i-vostri-soldi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/moodmedia.com\\\/it\\\/risorse-it\\\/ristorante-av-come-ottenere-il-massimo-per-i-vostri-soldi\\\/\"},\"author\":{\"name\":\"Brad Bond\",\"@id\":\"https:\\\/\\\/moodmedia.com\\\/it\\\/#\\\/schema\\\/person\\\/2c1d5d948a4c2afc406923edc1c7827d\"},\"headline\":\"Ristorante AV &#8211; Come ottenere il massimo per i vostri soldi\",\"datePublished\":\"2022-05-06T13:44:49+00:00\",\"dateModified\":\"2024-12-03T16:21:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/moodmedia.com\\\/it\\\/risorse-it\\\/ristorante-av-come-ottenere-il-massimo-per-i-vostri-soldi\\\/\"},\"wordCount\":1971,\"publisher\":{\"@id\":\"https:\\\/\\\/moodmedia.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/moodmedia.com\\\/it\\\/risorse-it\\\/ristorante-av-come-ottenere-il-massimo-per-i-vostri-soldi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/moodmedia.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/restaurant-av-ft.webp\",\"articleSection\":[\"Risorse\",\"Ristorante\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/moodmedia.com\\\/it\\\/risorse-it\\\/ristorante-av-come-ottenere-il-massimo-per-i-vostri-soldi\\\/\",\"url\":\"https:\\\/\\\/moodmedia.com\\\/it\\\/risorse-it\\\/ristorante-av-come-ottenere-il-massimo-per-i-vostri-soldi\\\/\",\"name\":\"Ristorante AV - Come ottenere il massimo per i vostri soldi | Mood Media Italia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/moodmedia.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/moodmedia.com\\\/it\\\/risorse-it\\\/ristorante-av-come-ottenere-il-massimo-per-i-vostri-soldi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/moodmedia.com\\\/it\\\/risorse-it\\\/ristorante-av-come-ottenere-il-massimo-per-i-vostri-soldi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/moodmedia.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/restaurant-av-ft.webp\",\"datePublished\":\"2022-05-06T13:44:49+00:00\",\"dateModified\":\"2024-12-03T16:21:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/moodmedia.com\\\/it\\\/risorse-it\\\/ristorante-av-come-ottenere-il-massimo-per-i-vostri-soldi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/moodmedia.com\\\/it\\\/risorse-it\\\/ristorante-av-come-ottenere-il-massimo-per-i-vostri-soldi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/moodmedia.com\\\/it\\\/risorse-it\\\/ristorante-av-come-ottenere-il-massimo-per-i-vostri-soldi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/moodmedia.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/restaurant-av-ft.webp\",\"contentUrl\":\"https:\\\/\\\/moodmedia.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/restaurant-av-ft.webp\",\"width\":1000,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/moodmedia.com\\\/it\\\/risorse-it\\\/ristorante-av-come-ottenere-il-massimo-per-i-vostri-soldi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/moodmedia.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ristorante AV &#8211; Come ottenere il massimo per i vostri soldi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/moodmedia.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/moodmedia.com\\\/it\\\/\",\"name\":\"Mood Media International\",\"description\":\"Experience. By Design\",\"publisher\":{\"@id\":\"https:\\\/\\\/moodmedia.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/moodmedia.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/moodmedia.com\\\/it\\\/#organization\",\"name\":\"Mood Media\",\"url\":\"https:\\\/\\\/moodmedia.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/moodmedia.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Mood Media\"},\"image\":{\"@id\":\"https:\\\/\\\/moodmedia.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/moodmediauk\\\/\",\"https:\\\/\\\/x.com\\\/MoodMedia_UK\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/mood-media-uk\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/moodmedia.com\\\/it\\\/#\\\/schema\\\/person\\\/2c1d5d948a4c2afc406923edc1c7827d\",\"name\":\"Brad Bond\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6674de3daef3ee4922ab97ff2a1a95c1d092443e6429ddaefc6f7733cf14e99c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6674de3daef3ee4922ab97ff2a1a95c1d092443e6429ddaefc6f7733cf14e99c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6674de3daef3ee4922ab97ff2a1a95c1d092443e6429ddaefc6f7733cf14e99c?s=96&d=mm&r=g\",\"caption\":\"Brad Bond\"},\"sameAs\":[\"https:\\\/\\\/moodmedia.com\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ristorante AV - Come ottenere il massimo per i vostri soldi | Mood Media Italia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"it_IT","og_type":"article","og_title":"Ristorante AV - Come ottenere il massimo per i vostri soldi","og_url":"https:\/\/moodmedia.com\/it\/risorse-it\/ristorante-av-come-ottenere-il-massimo-per-i-vostri-soldi\/","og_site_name":"Mood Media Italia","article_publisher":"https:\/\/www.facebook.com\/moodmediauk\/","article_published_time":"2022-05-06T13:44:49+00:00","article_modified_time":"2024-12-03T16:21:24+00:00","og_image":[{"width":1000,"height":500,"url":"https:\/\/moodmedia.com\/wp-content\/uploads\/2022\/05\/restaurant-av-ft.webp","type":"image\/webp"}],"author":"Brad Bond","twitter_card":"summary_large_image","twitter_creator":"@MoodMedia_UK","twitter_site":"@MoodMedia_UK","twitter_misc":{"Scritto da":"Brad Bond","Tempo di lettura stimato":"10 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/moodmedia.com\/it\/risorse-it\/ristorante-av-come-ottenere-il-massimo-per-i-vostri-soldi\/#article","isPartOf":{"@id":"https:\/\/moodmedia.com\/it\/risorse-it\/ristorante-av-come-ottenere-il-massimo-per-i-vostri-soldi\/"},"author":{"name":"Brad Bond","@id":"https:\/\/moodmedia.com\/it\/#\/schema\/person\/2c1d5d948a4c2afc406923edc1c7827d"},"headline":"Ristorante AV &#8211; Come ottenere il massimo per i vostri soldi","datePublished":"2022-05-06T13:44:49+00:00","dateModified":"2024-12-03T16:21:24+00:00","mainEntityOfPage":{"@id":"https:\/\/moodmedia.com\/it\/risorse-it\/ristorante-av-come-ottenere-il-massimo-per-i-vostri-soldi\/"},"wordCount":1971,"publisher":{"@id":"https:\/\/moodmedia.com\/it\/#organization"},"image":{"@id":"https:\/\/moodmedia.com\/it\/risorse-it\/ristorante-av-come-ottenere-il-massimo-per-i-vostri-soldi\/#primaryimage"},"thumbnailUrl":"https:\/\/moodmedia.com\/wp-content\/uploads\/2022\/05\/restaurant-av-ft.webp","articleSection":["Risorse","Ristorante"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/moodmedia.com\/it\/risorse-it\/ristorante-av-come-ottenere-il-massimo-per-i-vostri-soldi\/","url":"https:\/\/moodmedia.com\/it\/risorse-it\/ristorante-av-come-ottenere-il-massimo-per-i-vostri-soldi\/","name":"Ristorante AV - Come ottenere il massimo per i vostri soldi | Mood Media Italia","isPartOf":{"@id":"https:\/\/moodmedia.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/moodmedia.com\/it\/risorse-it\/ristorante-av-come-ottenere-il-massimo-per-i-vostri-soldi\/#primaryimage"},"image":{"@id":"https:\/\/moodmedia.com\/it\/risorse-it\/ristorante-av-come-ottenere-il-massimo-per-i-vostri-soldi\/#primaryimage"},"thumbnailUrl":"https:\/\/moodmedia.com\/wp-content\/uploads\/2022\/05\/restaurant-av-ft.webp","datePublished":"2022-05-06T13:44:49+00:00","dateModified":"2024-12-03T16:21:24+00:00","breadcrumb":{"@id":"https:\/\/moodmedia.com\/it\/risorse-it\/ristorante-av-come-ottenere-il-massimo-per-i-vostri-soldi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/moodmedia.com\/it\/risorse-it\/ristorante-av-come-ottenere-il-massimo-per-i-vostri-soldi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/moodmedia.com\/it\/risorse-it\/ristorante-av-come-ottenere-il-massimo-per-i-vostri-soldi\/#primaryimage","url":"https:\/\/moodmedia.com\/wp-content\/uploads\/2022\/05\/restaurant-av-ft.webp","contentUrl":"https:\/\/moodmedia.com\/wp-content\/uploads\/2022\/05\/restaurant-av-ft.webp","width":1000,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/moodmedia.com\/it\/risorse-it\/ristorante-av-come-ottenere-il-massimo-per-i-vostri-soldi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/moodmedia.com\/it\/"},{"@type":"ListItem","position":2,"name":"Ristorante AV &#8211; Come ottenere il massimo per i vostri soldi"}]},{"@type":"WebSite","@id":"https:\/\/moodmedia.com\/it\/#website","url":"https:\/\/moodmedia.com\/it\/","name":"Mood Media International","description":"Experience. By Design","publisher":{"@id":"https:\/\/moodmedia.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/moodmedia.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/moodmedia.com\/it\/#organization","name":"Mood Media","url":"https:\/\/moodmedia.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/moodmedia.com\/it\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Mood Media"},"image":{"@id":"https:\/\/moodmedia.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/moodmediauk\/","https:\/\/x.com\/MoodMedia_UK","https:\/\/www.linkedin.com\/company\/mood-media-uk\/"]},{"@type":"Person","@id":"https:\/\/moodmedia.com\/it\/#\/schema\/person\/2c1d5d948a4c2afc406923edc1c7827d","name":"Brad Bond","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/6674de3daef3ee4922ab97ff2a1a95c1d092443e6429ddaefc6f7733cf14e99c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6674de3daef3ee4922ab97ff2a1a95c1d092443e6429ddaefc6f7733cf14e99c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6674de3daef3ee4922ab97ff2a1a95c1d092443e6429ddaefc6f7733cf14e99c?s=96&d=mm&r=g","caption":"Brad Bond"},"sameAs":["https:\/\/moodmedia.com"]}]}},"_links":{"self":[{"href":"https:\/\/moodmedia.com\/it\/wp-json\/wp\/v2\/posts\/175801","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moodmedia.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/moodmedia.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/moodmedia.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/moodmedia.com\/it\/wp-json\/wp\/v2\/comments?post=175801"}],"version-history":[{"count":0,"href":"https:\/\/moodmedia.com\/it\/wp-json\/wp\/v2\/posts\/175801\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/moodmedia.com\/it\/wp-json\/wp\/v2\/media\/174731"}],"wp:attachment":[{"href":"https:\/\/moodmedia.com\/it\/wp-json\/wp\/v2\/media?parent=175801"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/moodmedia.com\/it\/wp-json\/wp\/v2\/categories?post=175801"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/moodmedia.com\/it\/wp-json\/wp\/v2\/tags?post=175801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}