{"id":341010,"date":"2023-02-07T14:26:15","date_gmt":"2023-02-07T14:26:15","guid":{"rendered":"https:\/\/moodmedia.com\/non-categorizzato\/i-punti-salienti-di-ise-2023-tendenze-tecnologia-e-innovazioni\/"},"modified":"2023-08-22T16:25:56","modified_gmt":"2023-08-22T15:25:56","slug":"i-punti-salienti-di-ise-2023-tendenze-tecnologia-e-innovazioni","status":"publish","type":"post","link":"https:\/\/moodmedia.com\/it\/blog-it\/obiettivo-del-settore\/i-punti-salienti-di-ise-2023-tendenze-tecnologia-e-innovazioni\/","title":{"rendered":"I punti salienti di ISE 2023: Tendenze, tecnologia e innovazioni"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Hero&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#5b5b5b&#8221; background_image=&#8221;https:\/\/moodmedia.com\/wp-content\/uploads\/2023\/02\/ise-hero.webp&#8221; background_position=&#8221;top_center&#8221; background_blend=&#8221;multiply&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; background_layout=&#8221;dark&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1 class=\"bold new-hero\">I PUNTI SALIENTI DELL&#8217;ISE 2023<span class=\"m-gradient\">: TENDENZE, TECNOLOGIA E INNOVAZIONI<\/span><\/h1>\n<p class=\"intro2\">Mentre si chiudono le porte di un altro fantastico evento ISE, riflettiamo sui momenti salienti.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row admin_label=&#8221;Articolo&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#eeeeee&#8221; custom_padding=&#8221;50px|50px|50px|50px|false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p class=\"intro2\">Questo \u00e8 stato il terzo anno di ISE nella sua nuova sede di Barcellona, e che anno \u00e8 stato. Con 58.107 visitatori unici provenienti da 155 Paesi, tra cui una visita del Re di Spagna, l&#8217;affluenza \u00e8 aumentata del 33% rispetto al ritorno post-COVID dello scorso anno. La vivacit\u00e0 di Barcellona, con la sua accogliente ospitalit\u00e0, la sua splendida architettura e il sole splendente (anche all&#8217;inizio di febbraio) \u00e8 innegabilmente diventata una fantastica cornice per la fiera leader mondiale dell&#8217;AV e dell&#8217;integrazione di sistemi.<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/moodmedia.com\/wp-content\/uploads\/2023\/02\/ISE-2023.webp&#8221; title_text=&#8221;ISE 2023&#8243; align=&#8221;center&#8221; force_fullwidth=&#8221;on&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p class=\"intro2\">Mentre si chiude un altro anno fantastico all&#8217;ISE, riflettiamo sulle tendenze emergenti, sulle ultime novit\u00e0 tecnologiche e sulle innovazioni pi\u00f9 interessanti che abbiamo visto nei padiglioni.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;2_5,3_5&#8243; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/moodmedia.com\/wp-content\/uploads\/2023\/02\/LG-Sustainability.webp&#8221; title_text=&#8221;LG Sostenibilit\u00e0&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2><b>L&#8217;ecologia conviene<\/b><\/h2>\n<p>Parlare di segnaletica ecologica non \u00e8 una novit\u00e0 nel mondo dell&#8217;AV, ma lo \u00e8 vedere i fornitori e di conseguenza i marchi mettere in pratica questi discorsi. Ci\u00f2 che ha colpito dell&#8217;evento di quest&#8217;anno \u00e8 stata l&#8217;enorme quantit\u00e0 di informazioni, campagne e offerte di prodotti dedicati alla sostenibilit\u00e0 e a cosa significa e cosa serve per essere verdi in un settore notoriamente poco verde.<\/p>\n<p>Nel 2022, <strong>Jonathan Wharrad, VP Global Brand Experience, Advanced Solutions Group<\/strong> di Mood, \u00e8 intervenuto nell&#8217;ambito del panel del <strong>DSS ISE<\/strong> sul tema della sostenibilit\u00e0 nella segnaletica e sulla sua accelerazione fino a diventare un elemento non negoziabile. Come ha detto Jonathan, per gli integratori come Mood Media, tutto si riduce alla collaborazione con partner esperti che prendono sul serio l&#8217;argomento e creano prodotti che soddisfano le esigenze in continua evoluzione dei consumatori.<\/p>\n<p>Camminando per i corridoi quest&#8217;anno, si \u00e8 avuta una sensazione schiacciante che la segnaletica verde sia diventata pienamente radicata, come detto, non negoziabile. L&#8217;intera facciata dello stand di Samsung, riservato ai soli partecipanti registrati, era ricoperta di impegni di sostenibilit\u00e0, promesse e prove del loro impegno eco-consapevole nell&#8217;affrontare il ciclo di vita dei prodotti e nel raggiungere emissioni nette pari a zero.  L&#8217;approccio di <strong>LG<\/strong>si \u00e8 concentrato sui vantaggi per il consumatore, con schermi tattili incorporati in schermi rivestiti di truciolato che mostrano cruscotti di risparmio energetico basati sull&#8217;utilizzo dell&#8217;energia a cui tutti i clienti LG avranno accesso.<\/p>\n<p>Nel frattempo, la gamma di display ad alta luminosit\u00e0 di <b>DynaScan<\/b>ha dimostrato che una maggiore dimensione e luminosit\u00e0 non significa necessariamente una minore efficienza energetica. Infatti, confrontando i watt per nit, i display ad alta luminosit\u00e0 DynaScan consumano il 45% in meno rispetto alla media del settore grazie ai materiali utilizzati, al controllo termico, alla regolazione intelligente della luminosit\u00e0 e agli algoritmi proprietari.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row admin_label=&#8221;Articolo&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/moodmedia.com\/wp-content\/uploads\/2023\/02\/DynaScan.webp&#8221; title_text=&#8221;DynaScan&#8221; align=&#8221;center&#8221; force_fullwidth=&#8221;on&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Per quanto riguarda <strong>Philips<\/strong>, il pezzo forte \u00e8 stato sicuramente il nuovo display e-paper Philips Tableaux. Philips \u00e8 il primo grande produttore a portare sul mercato una soluzione e-paper compatibile con la segnaletica digitale e offre una soluzione quasi priva di energia. Come? Il Tableaux Philips consuma quasi zero elettricit\u00e0 quando visualizza lo stesso contenuto e pu\u00f2 funzionare per molto tempo senza alimentazione.<\/p>\n<p>Se il contenuto viene modificato, lo schermo pu\u00f2 essere collegato all&#8217;alimentazione per un breve periodo, per poi continuare a funzionare per lunghi periodi. Quando \u00e8 necessario cambiare frequentemente i contenuti, il sistema pu\u00f2 rimanere collegato alla rete elettrica e consumare pochissima energia.<\/p>\n<p>Philips ritiene che i display Tableaux siano progettati in modo tale da offrire un significativo risparmio energetico ai clienti con le giuste esigenze, come quelli di ristoranti\/QSR che devono visualizzare i menu o quelli che necessitano di un mezzo per visualizzare orari o aperture che cambiano di rado, oltre a rendere le soluzioni di segnaletica digitale accessibili agli stabilimenti privi di elettricit\u00e0.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2><strong>La gestione remota \u00e8 la nuova gestione dei contenuti<\/strong><\/h2>\n<p>Con lo sviluppo della tecnologia, cresce anche il desiderio di rendere tutto pi\u00f9 veloce, semplice ed efficiente, e questo non si limita pi\u00f9 alla gestione dei contenuti. Era chiaro che la <strong>gestione remota e il monitoraggio delle prestazioni<\/strong> sarebbero presto diventati una grande aspettativa dei consumatori, e fornitori come <strong>Philips<\/strong> e <strong>Powersoft<\/strong> si sono gi\u00e0 mossi per soddisfare tali richieste.<\/p>\n<p>Per Philips, il lancio ufficiale di PPDS Wave, la piattaforma di gestione basata su cloud del marchio, ha avuto luogo quest&#8217;anno presso il suo stand. Per dimostrare che Wave non \u00e8 un semplice strumento di monitoraggio, ma ha molteplici opzioni di controllo, tra cui le funzionalit\u00e0 di risparmio energetico, Philips ha presentato due display, ciascuno collegato a un contatore elettrico. Wave ha ottimizzato il consumo energetico su uno schermo, ma non sull&#8217;altro. Dopo mezza giornata, il consumo energetico del display Wave era gi\u00e0 poco meno della met\u00e0 di quello della sua controparte.<\/p>\n<p>Allo stesso modo, Powersoft, leader mondiale nella produzione di amplificatori di potenza pro-audio leggeri ed efficienti dal punto di vista energetico, ha presentato il lancio di Powersoft Cloud, Universo, il proprio sistema di gestione remota che consentir\u00e0 il monitoraggio a distanza, gli aggiornamenti, l&#8217;archiviazione online dei progetti e l&#8217;accesso remoto a tutte le installazioni Powersoft, ponendo fine ai lunghi viaggi nei siti di installazione per eseguire semplici aggiornamenti degli amplificatori.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/moodmedia.com\/wp-content\/uploads\/2023\/02\/Philips-Tableaux.webp&#8221; title_text=&#8221;Philips Tableaux&#8221; force_fullwidth=&#8221;on&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row admin_label=&#8221;Articolo&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/moodmedia.com\/wp-content\/uploads\/2023\/02\/Powersoft.webp&#8221; title_text=&#8221;Powersoft&#8221; align=&#8221;center&#8221; force_fullwidth=&#8221;on&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Per quanto riguarda il miglioramento dell&#8217;efficienza e il risparmio di tempo (e di costi), la nostra piattaforma CMS proprietaria Mood Harmony \u00e8 stata recentemente sottoposta a un aggiornamento per sviluppare una versione System-on-Chip (SOC) che supporta gli schermi intelligenti Philips Smart TV e Samsung Tizen, nonch\u00e9 BrightSign OS, eliminando cos\u00ec la necessit\u00e0 di un lettore multimediale esterno. Ci\u00f2 significa che l&#8217;accesso e la gestione dei contenuti sugli schermi sono ora pi\u00f9 semplici ed economici, migliorando l&#8217;affidabilit\u00e0 e riducendo i costi di implementazione.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2><b>Nuovi modi di lavorare<\/b><\/h2>\n<p>Un altro punto focale dell&#8217;ISE 2023 \u00e8 stato naturalmente l&#8217;<strong>esperienza lavorativa ibrida.<\/strong> Non si pu\u00f2 negare l&#8217;impatto che la pandemia ha avuto su tutti gli aspetti della vita quotidiana, ma soprattutto sul modo in cui lavoriamo. La tradizionale vita d&#8217;ufficio 9-5 appartiene al passato per la maggior parte delle persone e il termine &#8220;lavoro ibrido&#8221; \u00e8 entrato nel linguaggio comune. Ma questo comporta delle sfide: tecnologia inaffidabile, connessioni wi-fi disordinate e qualit\u00e0 audiovisiva pessima. All&#8217;ISE \u00e8 emerso chiaramente che i fornitori non vogliono solo salvare la situazione dal punto di vista tecnologico, ma anche <strong>garantire che l&#8217;esperienza di lavoro ibrida diventi una comunit\u00e0, piuttosto che un semplice spazio di lavoro,<\/strong> che sia inclusiva di tutte le persone coinvolte, ovunque esse si trovino.<\/p>\n<p><strong>Sharp\/NEC<\/strong>  ha dedicato la maggior parte del suo stand a ricreare sale riunioni, sale riunioni e sale conferenze per mostrare le sue ultime integrazioni di segnaletica e di sistema (con aziende del calibro di Cisco e Microsoft) realizzate per rendere il lavoro ibrido pi\u00f9 facile, indipendentemente dalle dimensioni della stanza o dalla posizione dei partecipanti alle chiamate in conferenza, pi\u00f9 efficiente e senza intoppi.<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/moodmedia.com\/wp-content\/uploads\/2023\/02\/Sharp_NEC.webp&#8221; title_text=&#8221;Sharp_NEC&#8221; align=&#8221;center&#8221; force_fullwidth=&#8221;on&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]Anche le soluzioni <strong>BIAMP<\/strong> sono degne di nota. Dopo aver presentato il BIAMP Parl\u00e9 All-In-One Conferencing Bar alla fiera dello scorso anno, all&#8217;ISE 2023 l&#8217;azienda ha annunciato la nuova partnership con Lenovo per la fornitura di soluzioni basate su ThinkSmart Core e Controller Kit configurate per Microsoft Teams Rooms o Zoom Rooms, posizionandosi in modo deciso come fornitore di soluzioni complete nel mondo dei sistemi IT e AV aziendali. Presso lo stand erano esposti anche nuovi amplificatori. Questi amplificatori di forma pi\u00f9 piccola sono nati dalla richiesta da parte dei consumatori di prodotti pi\u00f9 efficienti dal punto di vista energetico e dalla possibilit\u00e0 di installare gli amplificatori in luoghi diversi dal semplice rack.[\/et_pb_text][et_pb_text _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2><strong>L&#8217;esperienza prima di tutto<\/strong><\/h2>\n<p>Anche se poche, alcune delle innovazioni pi\u00f9 teatrali esposte hanno dimostrato che oggi c&#8217;\u00e8 ancora posto per le soluzioni esperienziali nel settore.  EB-PU2220B di <strong>Epson<\/strong>, il proiettore laser da 20.000 lumen pi\u00f9 piccolo al mondo, ha impressionato gli spettatori con la sua attrazione immersiva per i visitatori, destinata a gallerie, musei e parchi a tema, mentre, proprio di fronte, Panasonic ha presentato la sua offerta di incontri digitali con l&#8217;arte.[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;2_3,1_3&#8243; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;2_3&#8243; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/moodmedia.com\/wp-content\/uploads\/2023\/02\/Epson.webp&#8221; title_text=&#8221;Epson&#8221; align=&#8221;center&#8221; force_fullwidth=&#8221;on&#8221; admin_label=&#8221;Image&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_video src=&#8221;https:\/\/us.moodmedia.com\/wp-content\/uploads\/2023\/02\/Panasonic-Projection-copy.mp4&#8243; image_src=&#8221;https:\/\/moodmedia.com\/wp-content\/uploads\/2023\/02\/panasonic-vid.webp&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_video][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]LG ha trasformato schermi di vetro di grandi dimensioni in opere d&#8217;arte multimediale con la sua impressionante gamma di soluzioni integrate. All&#8217;esterno dello stand, i visitatori sono stati accolti da 272 pollici di immagini magnifiche grazie a LG Magnit. La tecnologia Micro LED implementata con 0,78 Pixel Pitch vanta un&#8217;altissima definizione 8K e offre colori accurati, immersione nel nero e dettagli vividi per qualsiasi tipo di contenuto artistico digitale. [\/et_pb_text][et_pb_image src=&#8221;https:\/\/moodmedia.com\/wp-content\/uploads\/2023\/02\/LG-Magnit.webp&#8221; title_text=&#8221;LG Magnit&#8221; align=&#8221;center&#8221; force_fullwidth=&#8221;on&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]Proprio dietro l&#8217;angolo, l&#8217;iconico Transparent OLED Signage di LG ha fatto in modo che tutti gli occhi gravitassero sulle sue 56 unit\u00e0 di OLED da 55 pollici attaccate da un capo all&#8217;altro, mostrando immagini sbalorditive che incapsulavano il tema della mostra &#8220;Life, Be Bloomed&#8221; di LG.[\/et_pb_text][et_pb_image src=&#8221;https:\/\/moodmedia.com\/wp-content\/uploads\/2023\/02\/LG-Transparent-OLED.webp&#8221; title_text=&#8221;LG OLED trasparente&#8221; align=&#8221;center&#8221; force_fullwidth=&#8221;on&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]Infine, la scultura multimediale galleggiante CUBE LED, situata al centro dello stand, ha attirato l&#8217;attenzione sulla sua presenza grazie all&#8217;uso di potenti contenuti anamorfici, dando l&#8217;illusione di sfidare la gravit\u00e0 e anche i bordi dello schermo! I display LED LG possono essere installati in un design angolare a 90 gradi, rendendoli sostanzialmente privi di angoli. [\/et_pb_text][et_pb_video src=&#8221;https:\/\/us.moodmedia.com\/wp-content\/uploads\/2023\/02\/LG-Floating-CUBE-LED_1.mp4&#8243; image_src=&#8221;https:\/\/moodmedia.com\/wp-content\/uploads\/2023\/02\/lg-screen.webp&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_video][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,3_4&#8243; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text admin_label=&#8221;Text&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Nel padiglione 6, la startup spagnola <strong>Newtonlab Space<\/strong> ha dato vita a un vero e proprio spettacolo con The Shop Window, un impressionante dispositivo olografico che pu\u00f2 essere utilizzato in ambienti come le vetrine dei negozi o le istituzioni educative per portare l&#8217;esperienza dello spettatore a un livello completamente nuovo.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;3_4&#8243; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_video src=&#8221;https:\/\/us.moodmedia.com\/wp-content\/uploads\/2023\/02\/Newtonlab-Shop-Window.mp4&#8243; image_src=&#8221;https:\/\/moodmedia.com\/wp-content\/uploads\/2023\/02\/newton-lab.webp&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_video][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,1_4,1_2&#8243; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/moodmedia.com\/wp-content\/uploads\/2023\/02\/nexacare.webp&#8221; title_text=&#8221;nexacare&#8221; align=&#8221;center&#8221; force_fullwidth=&#8221;on&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_video src=&#8221;https:\/\/us.moodmedia.com\/wp-content\/uploads\/2023\/02\/nexmosphere.mp4&#8243; image_src=&#8221;https:\/\/moodmedia.com\/wp-content\/uploads\/2023\/02\/nexosphere.webp&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_video][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text admin_label=&#8221;Text&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Ma in termini di miglioramento dell&#8217;esperienza del cliente a un livello pi\u00f9 granulare e di uso quotidiano della segnaletica digitale, Nexmosphere \u00e8 stata una delle stelle pi\u00f9 brillanti dello show. Il loro stand, semplice ma innovativo, presentava una serie di soluzioni interattive perfette per ambienti come la vendita al dettaglio, il settore immobiliare e persino la sanit\u00e0.  Sono stati presentati i <strong>sensori azionati dal movimento<\/strong>, le notifiche di conteggio delle scorte tramite <strong>sensori di prossimit\u00e0 e la tecnologia Lift and Learn RFiD,<\/strong> ma la novit\u00e0 dell&#8217;ISE di quest&#8217;anno sono stati i <strong>sensori a gesti manuali<\/strong>. I sensori basati su telecamere che funzionano attraverso il vetro rispondono ai movimenti della mano, come lo strisciamento verso l&#8217;alto, verso il basso e persino il pollice in su, dove possono essere visualizzate CTA come codici QR o liste dei desideri.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text admin_label=&#8221;Text&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p class=\"intro2\">Tra tutte le parole d&#8217;ordine che circolavano nei padiglioni di ISE 2023, la sostenibilit\u00e0 era sicuramente la pi\u00f9 ricorrente e immaginiamo che lo sar\u00e0 anche per le prossime fiere. Mentre le pratiche sostenibili applicate ai prodotti di segnaletica digitale erano di vitale importanza, i vantaggi finanziari della segnaletica verde sembravano essere il punto chiave da dimostrare, in quanto i principali fornitori hanno accettato la sfida di assicurare ai consumatori che, a lungo termine, l&#8217;ecologia paga davvero.  <\/p>\n<p class=\"intro2\">Le innovazioni pi\u00f9 interessanti erano presenti, anche se non erano il punto focale. Come l&#8217;anno scorso, anche quest&#8217;anno i progressi pi\u00f9 innovativi sono stati nei dettagli, quei miglioramenti apparentemente piccoli ma cruciali che rendono la tecnologia pi\u00f9 intelligente, pi\u00f9 sostenibile e pi\u00f9 orientata ai dati. L&#8217;evoluzione in mostra, vista nella sua interezza, \u00e8 stata davvero impressionante.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Industry Page Contact&#8221; module_id=&#8221;contact&#8221; _builder_version=&#8221;4.16&#8243; collapsed=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; text_font=&#8221;||||||||&#8221; text_orientation=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2 class=\"bold\">CONNETTITI CON NOI<\/h2>\n<h4 class=\"intro\">Contattateci oggi stesso e migliorate l&#8217;esperienza del cliente nella vostra azienda.<\/h4>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Short Contact Form (light background)&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\nvar gform;gform||(document.addEventListener(\"gform_main_scripts_loaded\",function(){gform.scriptsLoaded=!0}),document.addEventListener(\"gform\/theme\/scripts_loaded\",function(){gform.themeScriptsLoaded=!0}),window.addEventListener(\"DOMContentLoaded\",function(){gform.domLoaded=!0}),gform={domLoaded:!1,scriptsLoaded:!1,themeScriptsLoaded:!1,isFormEditor:()=>\"function\"==typeof InitializeEditor,callIfLoaded:function(o){return!(!gform.domLoaded||!gform.scriptsLoaded||!gform.themeScriptsLoaded&&!gform.isFormEditor()||(gform.isFormEditor()&&console.warn(\"The use of gform.initializeOnLoaded() is deprecated in the form editor context and will be removed in Gravity Forms 3.1.\"),o(),0))},initializeOnLoaded:function(o){gform.callIfLoaded(o)||(document.addEventListener(\"gform_main_scripts_loaded\",()=>{gform.scriptsLoaded=!0,gform.callIfLoaded(o)}),document.addEventListener(\"gform\/theme\/scripts_loaded\",()=>{gform.themeScriptsLoaded=!0,gform.callIfLoaded(o)}),window.addEventListener(\"DOMContentLoaded\",()=>{gform.domLoaded=!0,gform.callIfLoaded(o)}))},hooks:{action:{},filter:{}},addAction:function(o,r,e,t){gform.addHook(\"action\",o,r,e,t)},addFilter:function(o,r,e,t){gform.addHook(\"filter\",o,r,e,t)},doAction:function(o){gform.doHook(\"action\",o,arguments)},applyFilters:function(o){return gform.doHook(\"filter\",o,arguments)},removeAction:function(o,r){gform.removeHook(\"action\",o,r)},removeFilter:function(o,r,e){gform.removeHook(\"filter\",o,r,e)},addHook:function(o,r,e,t,n){null==gform.hooks[o][r]&&(gform.hooks[o][r]=[]);var d=gform.hooks[o][r];null==n&&(n=r+\"_\"+d.length),gform.hooks[o][r].push({tag:n,callable:e,priority:t=null==t?10:t})},doHook:function(r,o,e){var t;if(e=Array.prototype.slice.call(e,1),null!=gform.hooks[r][o]&&((o=gform.hooks[r][o]).sort(function(o,r){return o.priority-r.priority}),o.forEach(function(o){\"function\"!=typeof(t=o.callable)&&(t=window[t]),\"action\"==r?t.apply(null,e):e[0]=t.apply(null,e)})),\"filter\"==r)return e[0]},removeHook:function(o,r,t,n){var e;null!=gform.hooks[o][r]&&(e=(e=gform.hooks[o][r]).filter(function(o,r,e){return!!(null!=n&&n!=o.tag||null!=t&&t!=o.priority)}),gform.hooks[o][r]=e)}});\n\/* ]]> *\/\n<\/script>\n\n                <div class='gf_browser_gecko gform_wrapper gravity-theme gform-theme--no-framework' data-form-theme='gravity-theme' data-form-index='0' id='gform_wrapper_3' >\n                        <div class='gform_heading'>\n\t\t\t\t\t\t\t<p class='gform_required_legend'>&quot;<span class=\"gfield_required gfield_required_asterisk\">*<\/span>&quot; indica i campi obbligatori<\/p>\n                        <\/div><form method='post' enctype='multipart\/form-data'  id='gform_3'  action='\/it\/wp-json\/wp\/v2\/posts\/341010' data-formid='3' novalidate>\n                        <div class='gform-body gform_body'><div id='gform_fields_3' class='gform_fields top_label form_sublabel_below description_below validation_below'><div id=\"field_3_41\" class=\"gfield gfield--type-honeypot gform_validation_container field_sublabel_below gfield--has-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_3_41'>Name<\/label><div class='ginput_container'><input name='input_41' id='input_3_41' type='text' value='' autocomplete='new-password'\/><\/div><div class='gfield_description' id='gfield_description_3_41'>Questo campo serve per la convalida e dovrebbe essere lasciato inalterato.<\/div><\/div><fieldset id=\"field_3_1\" class=\"gfield gfield--type-name gfield--input-type-name gfield_contains_required field_sublabel_hidden_label gfield--no-description field_description_below hidden_label field_validation_below gfield_visibility_visible\"  ><legend class='gfield_label gform-field-label gfield_label_before_complex' >Nome<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/legend><div class='ginput_complex ginput_container ginput_container--name no_prefix has_first_name no_middle_name has_last_name no_suffix gf_name_has_2 ginput_container_name gform-grid-row' id='input_3_1'>\n                            \n                            <span id='input_3_1_3_container' class='name_first gform-grid-col gform-grid-col--size-auto' >\n                                                    <input type='text' name='input_1.3' id='input_3_1_3' value=''   aria-required='true'   placeholder='Nome'  \/>\n                                                    <label for='input_3_1_3' class='gform-field-label gform-field-label--type-sub hidden_sub_label screen-reader-text'>Nome<\/label>\n                                                <\/span>\n                            \n                            <span id='input_3_1_6_container' class='name_last gform-grid-col gform-grid-col--size-auto' >\n                                                    <input type='text' name='input_1.6' id='input_3_1_6' value=''   aria-required='true'   placeholder='Cognome'  \/>\n                                                    <label for='input_3_1_6' class='gform-field-label gform-field-label--type-sub hidden_sub_label screen-reader-text'>Cognome<\/label>\n                                                <\/span>\n                            \n                        <\/div><\/fieldset><div id=\"field_3_2\" class=\"gfield gfield--type-email gfield--input-type-email gfield--width-half gfield_contains_required field_sublabel_below gfield--no-description field_description_below hidden_label field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_3_2'>Email<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_email'>\n                            <input name='input_2' id='input_3_2' type='email' value='' class='large'   placeholder='Email' aria-required=\"true\" aria-invalid=\"false\"  \/>\n                        <\/div><\/div><div id=\"field_3_4\" class=\"gfield gfield--type-phone gfield--input-type-phone gfield--width-half gfield_contains_required field_sublabel_below gfield--no-description field_description_below hidden_label field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_3_4'>Telefono<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_phone'><input name='input_4' id='input_3_4' type='tel' value='' class='large'  placeholder='Telefono' aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/div><div id=\"field_3_3\" class=\"gfield gfield--type-text gfield--input-type-text gfield--width-half gfield_contains_required field_sublabel_below gfield--no-description field_description_below hidden_label field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_3_3'>Nome della societ\u00e0<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_3' id='input_3_3' type='text' value='' class='large'    placeholder='Nome della societ\u00e0' aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/div><div id=\"field_3_9\" class=\"gfield gfield--type-select gfield--input-type-select gfield--width-half gfield_contains_required field_sublabel_below gfield--no-description field_description_below hidden_label field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_3_9'>Numero di sedi<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_select'><select name='input_9' id='input_3_9' class='large gfield_select'    aria-required=\"true\" aria-invalid=\"false\" ><option value='' selected='selected' class='gf_placeholder'>Numero di sedi<\/option><option value='1' >1<\/option><option value='2-10' >2-10<\/option><option value='11-49' >11-49<\/option><option value='50+' >50+<\/option><\/select><\/div><\/div><div id=\"field_3_6\" class=\"gfield gfield--type-textarea gfield--input-type-textarea field_sublabel_below gfield--no-description field_description_below hidden_label field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_3_6'>Come possiamo aiutarvi?<\/label><div class='ginput_container ginput_container_textarea'><textarea name='input_6' id='input_3_6' class='textarea small'    placeholder='Come possiamo aiutarvi?'  aria-invalid=\"false\"   rows='10' cols='50'><\/textarea><\/div><\/div><fieldset id=\"field_3_14\" class=\"gfield gfield--type-consent gfield--type-choice gfield--input-type-consent gfield--width-full gfield_contains_required field_sublabel_below gfield--no-description field_description_below hidden_label field_validation_below gfield_visibility_visible\"  ><legend class='gfield_label gform-field-label gfield_label_before_complex' >Informativa sulla privacy<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/legend><div class='ginput_container ginput_container_consent'><input name='input_14.1' id='input_3_14_1' type='checkbox' value='1'   aria-required=\"true\" aria-invalid=\"false\"   \/> <label class=\"gform-field-label gform-field-label--type-inline gfield_consent_label\" for='input_3_14_1' >Accetto il trattamento dei miei dati personali in conformit\u00e0 con l'<a href=\"https:\/\/moodmedia.com\/it\/azienda\/politica-sulla-privacy\/\" target=\"_blank\">Informativa sulla privacy<\/a> (compresi i trasferimenti internazionali) e acconsento all'utilizzo delle informazioni da parte di Mood Media per contattarmi.<span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/label><input type='hidden' name='input_14.2' value='Accetto il trattamento dei miei dati personali in conformit\u00e0 con l&#039;&lt;a href=&quot;https:\/\/moodmedia.com\/it\/azienda\/politica-sulla-privacy\/&quot; target=&quot;_blank&quot;&gt;Informativa sulla privacy&lt;\/a&gt; (compresi i trasferimenti internazionali) e acconsento all&#039;utilizzo delle informazioni da parte di Mood Media per contattarmi.' class='gform_hidden' \/><input type='hidden' name='input_14.3' value='3' class='gform_hidden' \/><\/div><\/fieldset><fieldset id=\"field_3_15\" class=\"gfield gfield--type-consent gfield--type-choice gfield--input-type-consent gfield--width-full field_sublabel_below gfield--no-description field_description_below hidden_label field_validation_below gfield_visibility_visible\"  ><legend class='gfield_label gform-field-label gfield_label_before_complex' >Rimanere in contatto<\/legend><div class='ginput_container ginput_container_consent'><input name='input_15.1' id='input_3_15_1' type='checkbox' value='1'    aria-invalid=\"false\"   \/> <label class=\"gform-field-label gform-field-label--type-inline gfield_consent_label\" for='input_3_15_1' >Desidero ricevere via e-mail notizie rilevanti, informazioni sui prodotti o offerte speciali. \u00c8 possibile annullare l'iscrizione in qualsiasi momento utilizzando gli appositi link presenti in tutte le informazioni inviate.<\/label><input type='hidden' name='input_15.2' value='Desidero ricevere via e-mail notizie rilevanti, informazioni sui prodotti o offerte speciali. \u00c8 possibile annullare l&#039;iscrizione in qualsiasi momento utilizzando gli appositi link presenti in tutte le informazioni inviate.' class='gform_hidden' \/><input type='hidden' name='input_15.3' value='3' class='gform_hidden' \/><\/div><\/fieldset><div id=\"field_3_18\" class=\"gfield gfield--type-captcha gfield--input-type-captcha gfield--width-full field_sublabel_below gfield--no-description field_description_below hidden_label field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_3_18'>CAPTCHA<\/label><div id='input_3_18' class='ginput_container ginput_recaptcha' data-sitekey='6Lfv6n8bAAAAAEtmA_JMn8-9T65gbem1F5Q9T6fQ'  data-theme='light' data-tabindex='-1' data-size='invisible' data-badge='bottomright'><\/div><\/div><div id=\"field_3_24\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gfield--width-full gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_24' id='input_3_24' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='Web - INTL' \/><\/div><\/div><div id=\"field_3_17\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_17' id='input_3_17' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='it' \/><\/div><\/div><div id=\"field_3_39\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gfield--width-full gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_39' id='input_3_39' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/div><div id=\"field_3_20\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gfield--width-full gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_20' id='input_3_20' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/div><div id=\"field_3_21\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gfield--width-full gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_21' id='input_3_21' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/div><div id=\"field_3_19\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gfield--width-full gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_19' id='input_3_19' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/div><div id=\"field_3_23\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gfield--width-full gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_23' id='input_3_23' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/div><div id=\"field_3_22\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gfield--width-full gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_22' id='input_3_22' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/div><div id=\"field_3_36\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gfield--width-full gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_36' id='input_3_36' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/div><div id=\"field_3_16\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gfield--width-full gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_16' id='input_3_16' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='https:\/\/moodmedia.com\/it\/wp-json\/wp\/v2\/posts\/341010' \/><\/div><\/div><div id=\"field_3_28\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gfield--width-full gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_28' id='input_3_28' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='https:\/\/moodmedia.com\/it\/wp-json\/wp\/v2\/posts\/341010' \/><\/div><\/div><div id=\"field_3_25\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gfield--width-full gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_25' id='input_3_25' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/div><div id=\"field_3_26\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gfield--width-full gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_26' id='input_3_26' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/div><div id=\"field_3_27\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gfield--width-full gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_27' id='input_3_27' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/div><div id=\"field_3_40\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gfield--width-full gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_40' id='input_3_40' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/div><div id=\"field_3_29\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_29' id='input_3_29' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/div><div id=\"field_3_30\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_30' id='input_3_30' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/div><div id=\"field_3_33\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gfield--width-full gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_33' id='input_3_33' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/div><div id=\"field_3_32\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gfield--width-full gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_32' id='input_3_32' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/div><div id=\"field_3_31\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_31' id='input_3_31' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/div><div id=\"field_3_34\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_34' id='input_3_34' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/div><div id=\"field_3_35\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_35' id='input_3_35' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='https:\/\/moodmedia.com\/it\/wp-json\/wp\/v2\/posts\/341010' \/><\/div><\/div><div id=\"field_3_37\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_37' id='input_3_37' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/div><div id=\"field_3_38\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_38' id='input_3_38' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/div><\/div><\/div>\n        <div class='gform-footer gform_footer top_label'> <input type=\"submit\" id=\"gform_submit_button_3\" class=\"gform_button button submit-button\" onclick=\"gform.submission.handleButtonClick(this);\" data-submission-type=\"submit\" value=\"Invia\"> \n            <input type='hidden' class='gform_hidden' name='gform_submission_method' data-js='gform_submission_method_3' value='postback' \/>\n            <input type='hidden' class='gform_hidden' name='gform_theme' data-js='gform_theme_3' id='gform_theme_3' value='gravity-theme' \/>\n            <input type='hidden' class='gform_hidden' name='gform_style_settings' data-js='gform_style_settings_3' id='gform_style_settings_3' value='[]' \/>\n            <input type='hidden' class='gform_hidden' name='is_submit_3' value='1' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submit' value='3' \/>\n            \n            <input type='hidden' class='gform_hidden' name='gform_currency' data-currency='EUR' value='7kQuj4s4cv70+2INWVqCoaDC5uWsRpxMIzW12T4gjA3q1pbKRW6XBENJwr+NlV9hfq6bvCu9hMGf276M6uWFaXwoh6iQ\/jFYZWq9oFujk8bxmrY=' \/>\n            <input type='hidden' class='gform_hidden' name='gform_unique_id' value='' \/>\n            <input type='hidden' class='gform_hidden' name='state_3' value='WyJ7XCIxNC4xXCI6XCIwZWI5NmJkYTliNmQ0NGVjZWM5OTk3MDgzNzFmZGFiZFwiLFwiMTQuMlwiOlwiNmRlOTAyNmVhN2JiNmE2NmQxNzNlNjgzMTVlMWRhMjlcIixcIjE0LjNcIjpcIjRiMjM4NDEzMjVlOGQ1MTU1YWJiZjJlMzg1YzhkOGFmXCIsXCIxNS4xXCI6XCIwZWI5NmJkYTliNmQ0NGVjZWM5OTk3MDgzNzFmZGFiZFwiLFwiMTUuMlwiOlwiZWVmY2JjYzBhM2FiZThhYjA0MWFkMmY4NTkyYjAwN2VcIixcIjE1LjNcIjpcIjRiMjM4NDEzMjVlOGQ1MTU1YWJiZjJlMzg1YzhkOGFmXCJ9IiwiZDJhYTlhZmNmYzNhY2U1MzA4MDk0ODEwYWM0YzQ1ZjkiXQ==' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_target_page_number_3' id='gform_target_page_number_3' value='0' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_source_page_number_3' id='gform_source_page_number_3' value='1' \/>\n            <input type='hidden' name='gform_field_values' value='' \/>\n            \n        <\/div>\n                        <\/form>\n                        <\/div><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n gform.initializeOnLoaded( function() {gformInitSpinner( 3, 'https:\/\/moodmedia.com\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery('#gform_ajax_frame_3').on('load',function(){var contents = jQuery(this).contents().find('*').html();var is_postback = contents.indexOf('GF_AJAX_POSTBACK') >= 0;if(!is_postback){return;}var form_content = jQuery(this).contents().find('#gform_wrapper_3');var is_confirmation = jQuery(this).contents().find('#gform_confirmation_wrapper_3').length > 0;var is_redirect = contents.indexOf('gformRedirect(){') >= 0;var is_form = form_content.length > 0 && ! is_redirect && ! is_confirmation;var mt = parseInt(jQuery('html').css('margin-top'), 10) + parseInt(jQuery('body').css('margin-top'), 10) + 100;if(is_form){jQuery('#gform_wrapper_3').html(form_content.html());if(form_content.hasClass('gform_validation_error')){jQuery('#gform_wrapper_3').addClass('gform_validation_error');} else {jQuery('#gform_wrapper_3').removeClass('gform_validation_error');}setTimeout( function() { \/* delay the scroll by 50 milliseconds to fix a bug in chrome *\/  }, 50 );if(window['gformInitDatepicker']) {gformInitDatepicker();}if(window['gformInitPriceFields']) {gformInitPriceFields();}var current_page = jQuery('#gform_source_page_number_3').val();gformInitSpinner( 3, 'https:\/\/moodmedia.com\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery(document).trigger('gform_page_loaded', [3, current_page]);window['gf_submitting_3'] = false;}else if(!is_redirect){var confirmation_content = jQuery(this).contents().find('.GF_AJAX_POSTBACK').html();if(!confirmation_content){confirmation_content = contents;}jQuery('#gform_wrapper_3').replaceWith(confirmation_content);jQuery(document).trigger('gform_confirmation_loaded', [3]);window['gf_submitting_3'] = false;wp.a11y.speak(jQuery('#gform_confirmation_message_3').text());}else{jQuery('#gform_3').append(contents);if(window['gformRedirect']) {gformRedirect();}}jQuery(document).trigger(\"gform_pre_post_render\", [{ formId: \"3\", currentPage: \"current_page\", abort: function() { this.preventDefault(); } }]);        if (event && event.defaultPrevented) {                return;        }        const gformWrapperDiv = document.getElementById( \"gform_wrapper_3\" );        if ( gformWrapperDiv ) {            const visibilitySpan = document.createElement( \"span\" );            visibilitySpan.id = \"gform_visibility_test_3\";            gformWrapperDiv.insertAdjacentElement( \"afterend\", visibilitySpan );        }        const visibilityTestDiv = document.getElementById( \"gform_visibility_test_3\" );        let postRenderFired = false;        function triggerPostRender() {            if ( postRenderFired ) {                return;            }            postRenderFired = true;            gform.core.triggerPostRenderEvents( 3, current_page );            if ( visibilityTestDiv ) {                visibilityTestDiv.parentNode.removeChild( visibilityTestDiv );            }        }        function debounce( func, wait, immediate ) {            var timeout;            return function() {                var context = this, args = arguments;                var later = function() {                    timeout = null;                    if ( !immediate ) func.apply( context, args );                };                var callNow = immediate && !timeout;                clearTimeout( timeout );                timeout = setTimeout( later, wait );                if ( callNow ) func.apply( context, args );            };        }        const debouncedTriggerPostRender = debounce( function() {            triggerPostRender();        }, 200 );        if ( visibilityTestDiv && visibilityTestDiv.offsetParent === null ) {            const observer = new MutationObserver( ( mutations ) => {                mutations.forEach( ( mutation ) => {                    if ( mutation.type === 'attributes' && visibilityTestDiv.offsetParent !== null ) {                        debouncedTriggerPostRender();                        observer.disconnect();                    }                });            });            observer.observe( document.body, {                attributes: true,                childList: false,                subtree: true,                attributeFilter: [ 'style', 'class' ],            });        } else {            triggerPostRender();        }    } );} ); \n\/* ]]> *\/\n<\/script>\n\n    <script>\n        jQuery( document ).ready(function() {\n        setTimeout(() => { Cookies.get(\"traffic_source\") ? jQuery('[id=\"input_3_39\"]').val(decodeURIComponent(sanitizeInput(Cookies.get(\"traffic_source\")) ?? '')) : '';\nCookies.get(\"utm_source\") ? jQuery('[id=\"input_3_20\"]').val(decodeURIComponent(sanitizeInput(Cookies.get(\"utm_source\")) ?? '')) : '';\nCookies.get(\"utm_medium\") ? jQuery('[id=\"input_3_21\"]').val(decodeURIComponent(sanitizeInput(Cookies.get(\"utm_medium\")) ?? '')) : '';\nCookies.get(\"utm_campaign\") ? jQuery('[id=\"input_3_19\"]').val(decodeURIComponent(sanitizeInput(Cookies.get(\"utm_campaign\")) ?? '')) : '';\nCookies.get(\"utm_content\") ? jQuery('[id=\"input_3_23\"]').val(decodeURIComponent(sanitizeInput(Cookies.get(\"utm_content\")) ?? '')) : '';\nCookies.get(\"utm_term\") ? jQuery('[id=\"input_3_22\"]').val(decodeURIComponent(sanitizeInput(Cookies.get(\"utm_term\")) ?? '')) : '';\nCookies.get(\"handl_ref\") ? jQuery('[id=\"input_3_36\"]').val(decodeURIComponent(sanitizeInput(Cookies.get(\"handl_ref\")) ?? '')) : '';\nCookies.get(\"gclid\") ? jQuery('[id=\"input_3_25\"]').val(decodeURIComponent(sanitizeInput(Cookies.get(\"gclid\")) ?? '')) : '';\nCookies.get(\"fbclid\") ? jQuery('[id=\"input_3_26\"]').val(decodeURIComponent(sanitizeInput(Cookies.get(\"fbclid\")) ?? '')) : '';\nCookies.get(\"msclkid\") ? jQuery('[id=\"input_3_27\"]').val(decodeURIComponent(sanitizeInput(Cookies.get(\"msclkid\")) ?? '')) : '';\nCookies.get(\"first_traffic_source\") ? jQuery('[id=\"input_3_40\"]').val(decodeURIComponent(sanitizeInput(Cookies.get(\"first_traffic_source\")) ?? '')) : '';\nCookies.get(\"first_utm_source\") ? jQuery('[id=\"input_3_29\"]').val(decodeURIComponent(sanitizeInput(Cookies.get(\"first_utm_source\")) ?? '')) : '';\nCookies.get(\"first_utm_medium\") ? jQuery('[id=\"input_3_30\"]').val(decodeURIComponent(sanitizeInput(Cookies.get(\"first_utm_medium\")) ?? '')) : '';\nCookies.get(\"first_utm_campaign\") ? jQuery('[id=\"input_3_33\"]').val(decodeURIComponent(sanitizeInput(Cookies.get(\"first_utm_campaign\")) ?? '')) : '';\nCookies.get(\"first_utm_content\") ? jQuery('[id=\"input_3_32\"]').val(decodeURIComponent(sanitizeInput(Cookies.get(\"first_utm_content\")) ?? '')) : '';\nCookies.get(\"first_utm_term\") ? jQuery('[id=\"input_3_31\"]').val(decodeURIComponent(sanitizeInput(Cookies.get(\"first_utm_term\")) ?? '')) : '';\nCookies.get(\"handl_original_ref\") ? jQuery('[id=\"input_3_34\"]').val(decodeURIComponent(sanitizeInput(Cookies.get(\"handl_original_ref\")) ?? '')) : '';\nCookies.get(\"handl_landing_page\") ? jQuery('[id=\"input_3_35\"]').val(decodeURIComponent(sanitizeInput(Cookies.get(\"handl_landing_page\")) ?? '')) : '';\nCookies.get(\"organic_source\") ? jQuery('[id=\"input_3_37\"]').val(decodeURIComponent(sanitizeInput(Cookies.get(\"organic_source\")) ?? '')) : '';\nCookies.get(\"organic_source_str\") ? jQuery('[id=\"input_3_38\"]').val(decodeURIComponent(sanitizeInput(Cookies.get(\"organic_source_str\")) ?? '')) : '';\n }, 1000);\n        })\n    <\/script>\n    \n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I PUNTI SALIENTI DELL&#8217;ISE 2023: TENDENZE, TECNOLOGIA E INNOVAZIONI Mentre si chiudono le porte di un altro fantastico evento ISE, riflettiamo sui momenti salienti.Questo \u00e8 stato il terzo anno di ISE nella sua nuova sede di Barcellona, e che anno \u00e8 stato. Con 58.107 visitatori unici provenienti da 155 Paesi, tra cui una visita del Re di Spagna, l&#8217;affluenza \u00e8 aumentata del 33% rispetto al ritorno post-COVID dello scorso anno. La vivacit\u00e0 di Barcellona, con la sua accogliente ospitalit\u00e0, la sua splendida architettura e il sole splendente (anche all&#8217;inizio di febbraio) \u00e8 innegabilmente diventata una fantastica cornice per la fiera leader mondiale dell&#8217;AV e dell&#8217;integrazione di sistemi.Mentre si chiude un altro anno fantastico all&#8217;ISE, riflettiamo sulle tendenze emergenti, sulle ultime novit\u00e0 tecnologiche e sulle innovazioni pi\u00f9 interessanti che abbiamo visto nei padiglioni.L&#8217;ecologia conviene Parlare di segnaletica ecologica non \u00e8 una novit\u00e0 nel mondo dell&#8217;AV, ma lo \u00e8 vedere i fornitori e di conseguenza i marchi mettere in pratica questi discorsi. Ci\u00f2 che ha colpito dell&#8217;evento di quest&#8217;anno \u00e8 stata l&#8217;enorme quantit\u00e0 di informazioni, campagne e offerte di prodotti dedicati alla sostenibilit\u00e0 e a cosa significa e cosa serve per essere verdi in un settore notoriamente poco verde. Nel 2022, Jonathan [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":340485,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[5355,5522],"tags":[],"class_list":["post-341010","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-it","category-obiettivo-del-settore"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.8 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>I punti salienti di ISE 2023: Tendenze, tecnologia e innovazioni | Mood Media Italia<\/title>\n<meta name=\"description\" content=\"Mentre si chiudono le porte di un altro fantastico evento ISE, riflettiamo sui momenti salienti.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"I punti salienti di ISE 2023: Tendenze, tecnologia e innovazioni\" \/>\n<meta property=\"og:url\" content=\"https:\/\/moodmedia.com\/it\/blog-it\/obiettivo-del-settore\/i-punti-salienti-di-ise-2023-tendenze-tecnologia-e-innovazioni\/\" \/>\n<meta property=\"og:site_name\" content=\"Mood Media Italia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/moodmediauk\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-07T14:26:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-22T15:25:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/moodmedia.com\/wp-content\/uploads\/2023\/02\/ise-ft.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"625\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Brad Bond\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@MoodMedia_UK\" \/>\n<meta name=\"twitter:site\" content=\"@MoodMedia_UK\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Brad Bond\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"15 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/moodmedia.com\\\/it\\\/blog-it\\\/obiettivo-del-settore\\\/i-punti-salienti-di-ise-2023-tendenze-tecnologia-e-innovazioni\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/moodmedia.com\\\/it\\\/blog-it\\\/obiettivo-del-settore\\\/i-punti-salienti-di-ise-2023-tendenze-tecnologia-e-innovazioni\\\/\"},\"author\":{\"name\":\"Brad Bond\",\"@id\":\"https:\\\/\\\/moodmedia.com\\\/it\\\/#\\\/schema\\\/person\\\/2c1d5d948a4c2afc406923edc1c7827d\"},\"headline\":\"I punti salienti di ISE 2023: Tendenze, tecnologia e innovazioni\",\"datePublished\":\"2023-02-07T14:26:15+00:00\",\"dateModified\":\"2023-08-22T15:25:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/moodmedia.com\\\/it\\\/blog-it\\\/obiettivo-del-settore\\\/i-punti-salienti-di-ise-2023-tendenze-tecnologia-e-innovazioni\\\/\"},\"wordCount\":3159,\"publisher\":{\"@id\":\"https:\\\/\\\/moodmedia.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/moodmedia.com\\\/it\\\/blog-it\\\/obiettivo-del-settore\\\/i-punti-salienti-di-ise-2023-tendenze-tecnologia-e-innovazioni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/moodmedia.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/ise-ft.webp\",\"articleSection\":[\"Blog\",\"Obiettivo del settore\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/moodmedia.com\\\/it\\\/blog-it\\\/obiettivo-del-settore\\\/i-punti-salienti-di-ise-2023-tendenze-tecnologia-e-innovazioni\\\/\",\"url\":\"https:\\\/\\\/moodmedia.com\\\/it\\\/blog-it\\\/obiettivo-del-settore\\\/i-punti-salienti-di-ise-2023-tendenze-tecnologia-e-innovazioni\\\/\",\"name\":\"I punti salienti di ISE 2023: Tendenze, tecnologia e innovazioni | Mood Media Italia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/moodmedia.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/moodmedia.com\\\/it\\\/blog-it\\\/obiettivo-del-settore\\\/i-punti-salienti-di-ise-2023-tendenze-tecnologia-e-innovazioni\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/moodmedia.com\\\/it\\\/blog-it\\\/obiettivo-del-settore\\\/i-punti-salienti-di-ise-2023-tendenze-tecnologia-e-innovazioni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/moodmedia.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/ise-ft.webp\",\"datePublished\":\"2023-02-07T14:26:15+00:00\",\"dateModified\":\"2023-08-22T15:25:56+00:00\",\"description\":\"Mentre si chiudono le porte di un altro fantastico evento ISE, riflettiamo sui momenti salienti.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/moodmedia.com\\\/it\\\/blog-it\\\/obiettivo-del-settore\\\/i-punti-salienti-di-ise-2023-tendenze-tecnologia-e-innovazioni\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/moodmedia.com\\\/it\\\/blog-it\\\/obiettivo-del-settore\\\/i-punti-salienti-di-ise-2023-tendenze-tecnologia-e-innovazioni\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/moodmedia.com\\\/it\\\/blog-it\\\/obiettivo-del-settore\\\/i-punti-salienti-di-ise-2023-tendenze-tecnologia-e-innovazioni\\\/#primaryimage\",\"url\":\"https:\\\/\\\/moodmedia.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/ise-ft.webp\",\"contentUrl\":\"https:\\\/\\\/moodmedia.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/ise-ft.webp\",\"width\":1000,\"height\":625},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/moodmedia.com\\\/it\\\/blog-it\\\/obiettivo-del-settore\\\/i-punti-salienti-di-ise-2023-tendenze-tecnologia-e-innovazioni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/moodmedia.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I punti salienti di ISE 2023: Tendenze, tecnologia e innovazioni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/moodmedia.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/moodmedia.com\\\/it\\\/\",\"name\":\"Mood Media International\",\"description\":\"Experience. By Design\",\"publisher\":{\"@id\":\"https:\\\/\\\/moodmedia.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/moodmedia.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/moodmedia.com\\\/it\\\/#organization\",\"name\":\"Mood Media\",\"url\":\"https:\\\/\\\/moodmedia.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/moodmedia.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/moodmedia.com\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/mood-media-logo-400.jpg\",\"contentUrl\":\"https:\\\/\\\/moodmedia.com\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/mood-media-logo-400.jpg\",\"width\":400,\"height\":115,\"caption\":\"Mood Media\"},\"image\":{\"@id\":\"https:\\\/\\\/moodmedia.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/moodmediauk\\\/\",\"https:\\\/\\\/x.com\\\/MoodMedia_UK\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/mood-media-uk\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/moodmedia.com\\\/it\\\/#\\\/schema\\\/person\\\/2c1d5d948a4c2afc406923edc1c7827d\",\"name\":\"Brad Bond\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6674de3daef3ee4922ab97ff2a1a95c1d092443e6429ddaefc6f7733cf14e99c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6674de3daef3ee4922ab97ff2a1a95c1d092443e6429ddaefc6f7733cf14e99c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6674de3daef3ee4922ab97ff2a1a95c1d092443e6429ddaefc6f7733cf14e99c?s=96&d=mm&r=g\",\"caption\":\"Brad Bond\"},\"sameAs\":[\"https:\\\/\\\/moodmedia.com\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"I punti salienti di ISE 2023: Tendenze, tecnologia e innovazioni | Mood Media Italia","description":"Mentre si chiudono le porte di un altro fantastico evento ISE, riflettiamo sui momenti salienti.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"it_IT","og_type":"article","og_title":"I punti salienti di ISE 2023: Tendenze, tecnologia e innovazioni","og_url":"https:\/\/moodmedia.com\/it\/blog-it\/obiettivo-del-settore\/i-punti-salienti-di-ise-2023-tendenze-tecnologia-e-innovazioni\/","og_site_name":"Mood Media Italia","article_publisher":"https:\/\/www.facebook.com\/moodmediauk\/","article_published_time":"2023-02-07T14:26:15+00:00","article_modified_time":"2023-08-22T15:25:56+00:00","og_image":[{"width":1000,"height":625,"url":"https:\/\/moodmedia.com\/wp-content\/uploads\/2023\/02\/ise-ft.webp","type":"image\/webp"}],"author":"Brad Bond","twitter_card":"summary_large_image","twitter_creator":"@MoodMedia_UK","twitter_site":"@MoodMedia_UK","twitter_misc":{"Scritto da":"Brad Bond","Tempo di lettura stimato":"15 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/moodmedia.com\/it\/blog-it\/obiettivo-del-settore\/i-punti-salienti-di-ise-2023-tendenze-tecnologia-e-innovazioni\/#article","isPartOf":{"@id":"https:\/\/moodmedia.com\/it\/blog-it\/obiettivo-del-settore\/i-punti-salienti-di-ise-2023-tendenze-tecnologia-e-innovazioni\/"},"author":{"name":"Brad Bond","@id":"https:\/\/moodmedia.com\/it\/#\/schema\/person\/2c1d5d948a4c2afc406923edc1c7827d"},"headline":"I punti salienti di ISE 2023: Tendenze, tecnologia e innovazioni","datePublished":"2023-02-07T14:26:15+00:00","dateModified":"2023-08-22T15:25:56+00:00","mainEntityOfPage":{"@id":"https:\/\/moodmedia.com\/it\/blog-it\/obiettivo-del-settore\/i-punti-salienti-di-ise-2023-tendenze-tecnologia-e-innovazioni\/"},"wordCount":3159,"publisher":{"@id":"https:\/\/moodmedia.com\/it\/#organization"},"image":{"@id":"https:\/\/moodmedia.com\/it\/blog-it\/obiettivo-del-settore\/i-punti-salienti-di-ise-2023-tendenze-tecnologia-e-innovazioni\/#primaryimage"},"thumbnailUrl":"https:\/\/moodmedia.com\/wp-content\/uploads\/2023\/02\/ise-ft.webp","articleSection":["Blog","Obiettivo del settore"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/moodmedia.com\/it\/blog-it\/obiettivo-del-settore\/i-punti-salienti-di-ise-2023-tendenze-tecnologia-e-innovazioni\/","url":"https:\/\/moodmedia.com\/it\/blog-it\/obiettivo-del-settore\/i-punti-salienti-di-ise-2023-tendenze-tecnologia-e-innovazioni\/","name":"I punti salienti di ISE 2023: Tendenze, tecnologia e innovazioni | Mood Media Italia","isPartOf":{"@id":"https:\/\/moodmedia.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/moodmedia.com\/it\/blog-it\/obiettivo-del-settore\/i-punti-salienti-di-ise-2023-tendenze-tecnologia-e-innovazioni\/#primaryimage"},"image":{"@id":"https:\/\/moodmedia.com\/it\/blog-it\/obiettivo-del-settore\/i-punti-salienti-di-ise-2023-tendenze-tecnologia-e-innovazioni\/#primaryimage"},"thumbnailUrl":"https:\/\/moodmedia.com\/wp-content\/uploads\/2023\/02\/ise-ft.webp","datePublished":"2023-02-07T14:26:15+00:00","dateModified":"2023-08-22T15:25:56+00:00","description":"Mentre si chiudono le porte di un altro fantastico evento ISE, riflettiamo sui momenti salienti.","breadcrumb":{"@id":"https:\/\/moodmedia.com\/it\/blog-it\/obiettivo-del-settore\/i-punti-salienti-di-ise-2023-tendenze-tecnologia-e-innovazioni\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/moodmedia.com\/it\/blog-it\/obiettivo-del-settore\/i-punti-salienti-di-ise-2023-tendenze-tecnologia-e-innovazioni\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/moodmedia.com\/it\/blog-it\/obiettivo-del-settore\/i-punti-salienti-di-ise-2023-tendenze-tecnologia-e-innovazioni\/#primaryimage","url":"https:\/\/moodmedia.com\/wp-content\/uploads\/2023\/02\/ise-ft.webp","contentUrl":"https:\/\/moodmedia.com\/wp-content\/uploads\/2023\/02\/ise-ft.webp","width":1000,"height":625},{"@type":"BreadcrumbList","@id":"https:\/\/moodmedia.com\/it\/blog-it\/obiettivo-del-settore\/i-punti-salienti-di-ise-2023-tendenze-tecnologia-e-innovazioni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/moodmedia.com\/it\/"},{"@type":"ListItem","position":2,"name":"I punti salienti di ISE 2023: Tendenze, tecnologia e innovazioni"}]},{"@type":"WebSite","@id":"https:\/\/moodmedia.com\/it\/#website","url":"https:\/\/moodmedia.com\/it\/","name":"Mood Media International","description":"Experience. By Design","publisher":{"@id":"https:\/\/moodmedia.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/moodmedia.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/moodmedia.com\/it\/#organization","name":"Mood Media","url":"https:\/\/moodmedia.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/moodmedia.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/moodmedia.com\/wp-content\/uploads\/2017\/10\/mood-media-logo-400.jpg","contentUrl":"https:\/\/moodmedia.com\/wp-content\/uploads\/2017\/10\/mood-media-logo-400.jpg","width":400,"height":115,"caption":"Mood Media"},"image":{"@id":"https:\/\/moodmedia.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/moodmediauk\/","https:\/\/x.com\/MoodMedia_UK","https:\/\/www.linkedin.com\/company\/mood-media-uk\/"]},{"@type":"Person","@id":"https:\/\/moodmedia.com\/it\/#\/schema\/person\/2c1d5d948a4c2afc406923edc1c7827d","name":"Brad Bond","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/6674de3daef3ee4922ab97ff2a1a95c1d092443e6429ddaefc6f7733cf14e99c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6674de3daef3ee4922ab97ff2a1a95c1d092443e6429ddaefc6f7733cf14e99c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6674de3daef3ee4922ab97ff2a1a95c1d092443e6429ddaefc6f7733cf14e99c?s=96&d=mm&r=g","caption":"Brad Bond"},"sameAs":["https:\/\/moodmedia.com"]}]}},"_links":{"self":[{"href":"https:\/\/moodmedia.com\/it\/wp-json\/wp\/v2\/posts\/341010","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moodmedia.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/moodmedia.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/moodmedia.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/moodmedia.com\/it\/wp-json\/wp\/v2\/comments?post=341010"}],"version-history":[{"count":0,"href":"https:\/\/moodmedia.com\/it\/wp-json\/wp\/v2\/posts\/341010\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/moodmedia.com\/it\/wp-json\/wp\/v2\/media\/340485"}],"wp:attachment":[{"href":"https:\/\/moodmedia.com\/it\/wp-json\/wp\/v2\/media?parent=341010"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/moodmedia.com\/it\/wp-json\/wp\/v2\/categories?post=341010"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/moodmedia.com\/it\/wp-json\/wp\/v2\/tags?post=341010"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}